{"id":7964,"date":"2019-03-01T16:20:00","date_gmt":"2019-03-01T19:20:00","guid":{"rendered":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/?p=7964"},"modified":"2026-05-07T16:21:02","modified_gmt":"2026-05-07T19:21:02","slug":"obras-na-rede-de-esgoto-da-rua-coronel-fernando-prestes-continuam-nos-dias-3-e-4-3","status":"publish","type":"post","link":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/2019\/03\/01\/obras-na-rede-de-esgoto-da-rua-coronel-fernando-prestes-continuam-nos-dias-3-e-4-3\/","title":{"rendered":"Obras na rede de esgoto da rua Coronel Fernando Prestes continuam nos dias 3 e 4\/3"},"content":{"rendered":"\n<p><em>Servi\u00e7os ser\u00e3o realizados no trecho pr\u00f3ximo ao Hospital Brasil com a rua Doze de Outubro e ocasionar\u00e1 interdi\u00e7\u00e3o das vias<\/em><\/p>\n\n\n\n<p><strong>Santo Andr\u00e9, 1 de mar\u00e7o de 2019 \u2013 Neste pr\u00f3ximo domingo e segunda-feira, do feriado de Carnaval (3 e 4\/3) as equipes do Semasa (Servi\u00e7o Municipal de Saneamento Ambiental de Santo Andr\u00e9) d\u00e3o continuidade \u00e0s obras na rede de esgoto da rua Coronel Fernando Prestes X rua Doze de Outubro (Vila Dora). Para realiza\u00e7\u00e3o dos trabalhos, ser\u00e1 necess\u00e1rio interditar totalmente a via, na altura do n\u00famero 1.177, entre 8h e 17h, nos dois dias. Os servi\u00e7os no local tiveram in\u00edcio no \u00faltimo 17 e s\u00e3o importantes para o sistema de esgotamento sanit\u00e1rio da regi\u00e3o.<\/strong><\/p>\n\n\n\n<p>Por tratar-se de uma via de intenso movimento, as obras s\u00f3 podem ser realizadas aos domingos ou feriados. A interdi\u00e7\u00e3o afetar\u00e1 ve\u00edculos que trafegam pela avenida Pereira Barreto, sentido Centro, e que queiram acessar a rua Fernando Prestes ou a rua Doze de Outubro. O tr\u00e2nsito de motoristas s\u00f3 ser\u00e1 permitido para ve\u00edculos em emerg\u00eancia, que desejam acesso ao Pronto Socorro do Hospital Brasil. Por isso, o local contar\u00e1 com agentes de tr\u00e2nsito do DET (Departamento de Engenharia de Tr\u00e1fego) para orienta\u00e7\u00e3o.<\/p>\n\n\n\n<p>Tamb\u00e9m ser\u00e3o afetadas as linhas de \u00f4nibus municipais B-63 e I-08. A SA Trans far\u00e1 o desvio dos coletivos por meio da rua Venezuela e depois com acesso novamente \u00e0 rua Fernando Prestes.<\/p>\n\n\n\n<p>Os motoristas que trafegam pela avenida Pereira Barreto e desejam acessar as ruas Doze de Outubro, Andradas ou Jos\u00e9 Benedito de Castro, dever\u00e3o continuar na via sentido Centro de Santo Andr\u00e9 e virar \u00e0 direita na rua Venezuela. Seguir pela Venezuela at\u00e9 a rua Porto Alegre e realizar o acesso \u00e0s demais ruas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Servi\u00e7os ser\u00e3o realizados no trecho pr\u00f3ximo ao Hospital Brasil com a rua Doze de Outubro e ocasionar\u00e1 interdi\u00e7\u00e3o das vias Santo Andr\u00e9, 1 de mar\u00e7o de 2019 \u2013 Neste pr\u00f3ximo domingo e segunda-feira, do feriado de Carnaval (3 e 4\/3) as equipes do Semasa (Servi\u00e7o Municipal de Saneamento Ambiental de Santo Andr\u00e9) d\u00e3o continuidade \u00e0s [&hellip;]<\/p>\n","protected":false},"author":60,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,8],"tags":[],"class_list":["post-7964","post","type-post","status-publish","format-standard","hentry","category-agua-e-esgoto","category-releases"],"_links":{"self":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/7964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/comments?post=7964"}],"version-history":[{"count":1,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/7964\/revisions"}],"predecessor-version":[{"id":7965,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/7964\/revisions\/7965"}],"wp:attachment":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/media?parent=7964"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/categories?post=7964"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/tags?post=7964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}