{"id":7962,"date":"2019-03-01T16:18:00","date_gmt":"2019-03-01T19:18:00","guid":{"rendered":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/?p=7962"},"modified":"2026-05-07T16:19:23","modified_gmt":"2026-05-07T19:19:23","slug":"veja-como-ficam-os-servicos-no-feriado-de-carnaval","status":"publish","type":"post","link":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/2019\/03\/01\/veja-como-ficam-os-servicos-no-feriado-de-carnaval\/","title":{"rendered":"Veja como ficam os servi\u00e7os no feriado de Carnaval"},"content":{"rendered":"\n<p><strong>Res\u00edduos S\u00f3lidos<\/strong><\/p>\n\n\n\n<p>Coleta porta a porta: normal<\/p>\n\n\n\n<p>Remo\u00e7\u00e3o de res\u00edduos de sa\u00fade<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>S\u00e1bado (2\/3) e ter\u00e7a-feira (5\/3): das 7h \u00e0s 10h<\/li>\n\n\n\n<li>Domingo (3\/3): n\u00e3o h\u00e1<\/li>\n\n\n\n<li>Segunda (4\/3) e Quarta-feira (6\/3): das 7h \u00e0s 15h (expediente normal)<\/li>\n<\/ul>\n\n\n\n<p>Recolha de animais mortos<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>S\u00e1bado\u00a0e ter\u00e7a-feira:\u00a0das 11h \u00e0s 15h.<\/li>\n\n\n\n<li>Domingo: n\u00e3o h\u00e1<\/li>\n\n\n\n<li>Segunda e Quarta-feira: das 9h \u00e0s 17h (expediente normal)<\/li>\n<\/ul>\n\n\n\n<p>Esta\u00e7\u00f5es de Coleta<\/p>\n\n\n\n<p>No s\u00e1bado, segunda e quarta-feira as Esta\u00e7\u00f5es de Coleta funcionam normalmente. No domingo e na ter\u00e7a-feira&nbsp;s\u00f3 funcionam&nbsp;as esta\u00e7\u00f5es que abrem aos domingos&nbsp;e&nbsp;feriados.&nbsp;Os endere\u00e7os&nbsp;e&nbsp;hor\u00e1rios de funcionamento&nbsp;<a href=\"https:\/\/www.semasa.sp.gov.br\/residuos\/coleta-domiciliar-2\/coleta-seletiva\/estacoes-de-coleta\/\">podem ser consultados aqui<\/a>.<\/p>\n\n\n\n<p><strong>Postos de Atendimento do Semasa<\/strong><\/p>\n\n\n\n<p>Os Postos de Atendimento n\u00e3o funcionam entre os dias 2 e 5\/3. O atendimento ao usu\u00e1rio retorna na quarta-feira (6\/3), a partir das 13h.<\/p>\n\n\n\n<p><strong>Central de Atendimento<\/strong><\/p>\n\n\n\n<p>Funciona normalmente durante todo o feriado, 24 horas por dia.<\/p>\n\n\n\n<p><strong>Expediente<\/strong><\/p>\n\n\n\n<p>N\u00e3o h\u00e1 expediente no Semasa, conforme portaria municipal. Os servi\u00e7os essenciais s\u00e3o mantidos em escala de plant\u00e3o. O expediente retorna na quarta-feira (6\/3), a partir das 13h.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Res\u00edduos S\u00f3lidos Coleta porta a porta: normal Remo\u00e7\u00e3o de res\u00edduos de sa\u00fade Recolha de animais mortos Esta\u00e7\u00f5es de Coleta No s\u00e1bado, segunda e quarta-feira as Esta\u00e7\u00f5es de Coleta funcionam normalmente. No domingo e na ter\u00e7a-feira&nbsp;s\u00f3 funcionam&nbsp;as esta\u00e7\u00f5es que abrem aos domingos&nbsp;e&nbsp;feriados.&nbsp;Os endere\u00e7os&nbsp;e&nbsp;hor\u00e1rios de funcionamento&nbsp;podem ser consultados aqui. Postos de Atendimento do Semasa Os Postos de [&hellip;]<\/p>\n","protected":false},"author":60,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,8],"tags":[],"class_list":["post-7962","post","type-post","status-publish","format-standard","hentry","category-agua-e-esgoto","category-releases"],"_links":{"self":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/7962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/comments?post=7962"}],"version-history":[{"count":1,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/7962\/revisions"}],"predecessor-version":[{"id":7963,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/7962\/revisions\/7963"}],"wp:attachment":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/media?parent=7962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/categories?post=7962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/tags?post=7962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}