{"id":7934,"date":"2019-02-20T15:52:00","date_gmt":"2019-02-20T18:52:00","guid":{"rendered":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/?p=7934"},"modified":"2026-05-06T15:55:59","modified_gmt":"2026-05-06T18:55:59","slug":"fique-atento-semasa-informa-manutencoes-do-dia-20-02-2019","status":"publish","type":"post","link":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/2019\/02\/20\/fique-atento-semasa-informa-manutencoes-do-dia-20-02-2019\/","title":{"rendered":"Fique atento: Semasa informa manuten\u00e7\u00f5es do dia 20\/02\/2019"},"content":{"rendered":"\n<p>O Semasa informa que, das 0h \u00e0s 13h de hoje, equipes da autarquia precisaram efetivar 2 fechamentos de \u00e1gua para realizar manuten\u00e7\u00f5es.<\/p>\n\n\n\n<p>No dia anterior, foram realizados 6 fechamentos para interven\u00e7\u00f5es.<\/p>\n\n\n\n<p>O objetivo dos servi\u00e7os \u00e9 consertar vazamentos e combater as perdas de \u00e1gua.<\/p>\n\n\n\n<p>Moradores do entorno dos pontos de manuten\u00e7\u00e3o podem ter problemas de abastecimento.<\/p>\n\n\n\n<p><strong>Confira os endere\u00e7os e hor\u00e1rios das manuten\u00e7\u00f5es.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>20\/02\/2019 \u2013 Das 0h \u00e0s 13h de hoje<\/td><td>In\u00edcio<\/td><td>T\u00e9rmino<\/td><\/tr><tr><td>Av. Marginal C\u00f3rrego Taioca (Jardim Stella)<\/td><td>10h35<\/td><td>11h20<\/td><\/tr><tr><td>Rua Camerun (Parque Orat\u00f3rio)<\/td><td>10h11<\/td><td>11h45<\/td><\/tr><tr><td><\/td><td><\/td><td><\/td><\/tr><tr><td>19\/02\/2019<\/td><td><\/td><td><\/td><\/tr><tr><td>Rua Boror\u00e9 (Vila Vit\u00f3ria)<\/td><td>15h18<\/td><td>16h55<\/td><\/tr><tr><td>Rua \u00c1guas Belas (Parque Capuava)<\/td><td>10h41<\/td><td>14h18<\/td><\/tr><tr><td>Rua Sebasti\u00e3o Pereira (Vila Vit\u00f3ria)<\/td><td>8h45<\/td><td>10h40<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Semasa informa que, das 0h \u00e0s 13h de hoje, equipes da autarquia precisaram efetivar 2 fechamentos de \u00e1gua para realizar manuten\u00e7\u00f5es. No dia anterior, foram realizados 6 fechamentos para interven\u00e7\u00f5es. O objetivo dos servi\u00e7os \u00e9 consertar vazamentos e combater as perdas de \u00e1gua. Moradores do entorno dos pontos de manuten\u00e7\u00e3o podem ter problemas de [&hellip;]<\/p>\n","protected":false},"author":60,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,8],"tags":[],"class_list":["post-7934","post","type-post","status-publish","format-standard","hentry","category-agua-e-esgoto","category-releases"],"_links":{"self":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/7934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/comments?post=7934"}],"version-history":[{"count":1,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/7934\/revisions"}],"predecessor-version":[{"id":7935,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/7934\/revisions\/7935"}],"wp:attachment":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/media?parent=7934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/categories?post=7934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/tags?post=7934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}