{"id":7674,"date":"2026-04-26T08:25:06","date_gmt":"2026-04-26T11:25:06","guid":{"rendered":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/?p=7674"},"modified":"2026-04-27T08:30:22","modified_gmt":"2026-04-27T11:30:22","slug":"santo-andre-aplica-48-autuacoes-durante-operacao-sono-tranquilo","status":"publish","type":"post","link":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/2026\/04\/26\/santo-andre-aplica-48-autuacoes-durante-operacao-sono-tranquilo\/","title":{"rendered":"Santo Andr\u00e9 aplica 48 autua\u00e7\u00f5es durante Opera\u00e7\u00e3o Sono Tranquilo"},"content":{"rendered":"\n<p><em>A\u00e7\u00e3o integrada entre Semasa, DCURb e GCM fiscalizou estabelecimentos, coibiu perturba\u00e7\u00e3o de sossego e recolheu 20 motos ao p\u00e1tio entre s\u00e1bado e domingo<\/em>\u00a0<\/p>\n\n\n\n<p>Santo Andr\u00e9, 26 de abril de 2026 &#8211; A Prefeitura de Santo Andr\u00e9 realizou, entre a noite de s\u00e1bado (25) e a madrugada deste domingo (26), mais uma edi\u00e7\u00e3o da Opera\u00e7\u00e3o Sono Tranquilo, com o objetivo de fiscalizar irregularidades e garantir o sossego da popula\u00e7\u00e3o. A a\u00e7\u00e3o, com maior n\u00famero de autua\u00e7\u00f5es at\u00e9 o momento, 48 no total, contou com a atua\u00e7\u00e3o integrada do Semasa (Servi\u00e7o Municipal de Saneamento Ambiental de Santo Andr\u00e9), do DCurb (Departamento de Controle Urbano) \u2013 ligado \u00e0 Secretaria de Desenvolvimento Urbano e Habita\u00e7\u00e3o \u2013 e da GCM (Guarda Civil Municipal).\u00a0<\/p>\n\n\n\n<p>Durante a opera\u00e7\u00e3o, foram registradas autua\u00e7\u00f5es em diversos pontos do munic\u00edpio, incluindo notifica\u00e7\u00f5es, advert\u00eancias e multas aplicadas por equipes da Fiscaliza\u00e7\u00e3o Ambiental do Semasa, do Departamento de Controle Urbano e da GCM, que atuou apurando tamb\u00e9m as infra\u00e7\u00f5es de tr\u00e2nsito. Ao todo, foram emitidas 12 multas (Autos de Infra\u00e7\u00e3o Ambiental) e tr\u00eas Advert\u00eancias Ambientais pelo Semasa; e quatro multas e tr\u00eas notifica\u00e7\u00f5es pelo DCurb.\u00a0<\/p>\n\n\n\n<p>\u201cO resultado desta edi\u00e7\u00e3o da Opera\u00e7\u00e3o Sono Tranquilo demonstra o compromisso firme da nossa gest\u00e3o com a qualidade de vida da popula\u00e7\u00e3o de Santo Andr\u00e9. Estamos intensificando as a\u00e7\u00f5es integradas de fiscaliza\u00e7\u00e3o para coibir irregularidades e garantir que o direito ao descanso e ao sossego dos moradores seja respeitado. Seguiremos atuando de forma rigorosa e cont\u00ednua, sempre com responsabilidade e di\u00e1logo, para construir uma cidade mais organizada, segura e acolhedora para todos&#8221;, afirma o prefeito Gilvan Ferreira.\u00a0<\/p>\n\n\n\n<p>A Guarda Civil Municipal tamb\u00e9m atuou de forma preventiva e operacional durante a a\u00e7\u00e3o, com 35 pessoas averiguadas, 27 autos de infra\u00e7\u00e3o de tr\u00e2nsito lavrados e 20 motocicletas removidas ao p\u00e1tio municipal.\u00a0<\/p>\n\n\n\n<p>As ocorr\u00eancias foram distribu\u00eddas em diferentes bairros, como Vila Pr\u00edncipe de Gales, Vila Palmares, Campestre, Jardim, Utinga, Jardim Santa Cristina, Jardim Guarar\u00e1, Santa Teresinha, Jardim Riviera, Parque Miami, Vila Curu\u00e7\u00e1, Parque Capuava, Parque Novo Orat\u00f3rio, Centro e Vila Su\u00ed\u00e7a.\u00a0<\/p>\n\n\n\n<p>Caso o mun\u00edcipe de Santo Andr\u00e9 seja incomodado por barulho excessivo em com\u00e9rcios, como bares, adegas, tabacarias, restaurantes, al\u00e9m de templos religiosos, obras e escolas de samba, a orienta\u00e7\u00e3o \u00e9 registrar den\u00fancia pelo site www.semasa.sp.gov.br, no momento em que ocorre a perturba\u00e7\u00e3o de sossego.\u00a0<\/p>\n\n\n\n<p>Tamb\u00e9m \u00e9 poss\u00edvel fazer a den\u00fancia \u2013 de forma sigilosa (por\u00e9m, n\u00e3o an\u00f4nima) \u2013 pela Central de Atendimento Telef\u00f4nico, nos n\u00fameros 0800-4848115 ou 4433-9300, de segunda a sexta, das 8h30 \u00e0s 16h.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A\u00e7\u00e3o integrada entre Semasa, DCURb e GCM fiscalizou estabelecimentos, coibiu perturba\u00e7\u00e3o de sossego e recolheu 20 motos ao p\u00e1tio entre s\u00e1bado e domingo\u00a0 Santo Andr\u00e9, 26 de abril de 2026 &#8211; A Prefeitura de Santo Andr\u00e9 realizou, entre a noite de s\u00e1bado (25) e a madrugada deste domingo (26), mais uma edi\u00e7\u00e3o da Opera\u00e7\u00e3o Sono [&hellip;]<\/p>\n","protected":false},"author":94,"featured_media":7680,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,8],"tags":[],"class_list":["post-7674","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fiscalizacao-ambiental","category-releases"],"_links":{"self":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/7674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/users\/94"}],"replies":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/comments?post=7674"}],"version-history":[{"count":1,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/7674\/revisions"}],"predecessor-version":[{"id":7676,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/7674\/revisions\/7676"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/media\/7680"}],"wp:attachment":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/media?parent=7674"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/categories?post=7674"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/tags?post=7674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}