{"id":7654,"date":"2019-02-07T16:49:00","date_gmt":"2019-02-07T18:49:00","guid":{"rendered":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/?p=7654"},"modified":"2026-04-23T16:50:02","modified_gmt":"2026-04-23T19:50:02","slug":"fique-atento-semasa-informa-manutencoes-do-dia-07-02-2019","status":"publish","type":"post","link":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/2019\/02\/07\/fique-atento-semasa-informa-manutencoes-do-dia-07-02-2019\/","title":{"rendered":"Fique atento: Semasa informa manuten\u00e7\u00f5es do dia 07\/02\/2019"},"content":{"rendered":"\n<p>O Semasa informa que, das 0h \u00e0s 13h de hoje, equipes da autarquia precisaram efetivar&nbsp; 2 fechamentos de \u00e1gua para realizar manuten\u00e7\u00f5es.<\/p>\n\n\n\n<p>No dia anterior, foi realizado 1 fechamento para interven\u00e7\u00f5es, uma ainda n\u00e3o finalizada.<\/p>\n\n\n\n<p>O objetivo dos servi\u00e7os \u00e9 consertar vazamentos e combater as perdas de \u00e1gua.<\/p>\n\n\n\n<p>Moradores do entorno dos pontos de manuten\u00e7\u00e3o podem ter problemas de abastecimento.<\/p>\n\n\n\n<p><strong>Confira os endere\u00e7os e hor\u00e1rios das manuten\u00e7\u00f5es.<\/strong><strong>&nbsp;<\/strong><strong>&nbsp;<\/strong><strong>&nbsp;<\/strong><strong>&nbsp;<\/strong><strong>&nbsp;<\/strong><strong>&nbsp;<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td><strong>07\/02\/2019 \u2013 Das 0h \u00e0s 13h de hoje<\/strong><\/td><td><strong>In\u00edcio<\/strong><\/td><td><strong>T\u00e9rmino<\/strong><\/td><\/tr><tr><td>Alameda dos Pinheiros (Campestre)<\/td><td>11h45<\/td><td>\u2013<\/td><\/tr><tr><td>Rua Cabu\u00e7u (Jardim do Est\u00e1dio)<\/td><td>10h07<\/td><td>\u2013<\/td><\/tr><tr><td><\/td><td><\/td><td><\/td><\/tr><tr><td><strong>06\/02\/2019<\/strong><\/td><td><strong>In\u00edcio<\/strong><\/td><td><strong>T\u00e9rmino<\/strong><\/td><\/tr><tr><td>Rua Rio Grande do Sul (Cidade S\u00e3o Jorge)<\/td><td>15h16<\/td><td>15h37<\/td><\/tr><\/tbody><\/table><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>O Semasa informa que, das 0h \u00e0s 13h de hoje, equipes da autarquia precisaram efetivar&nbsp; 2 fechamentos de \u00e1gua para realizar manuten\u00e7\u00f5es. No dia anterior, foi realizado 1 fechamento para interven\u00e7\u00f5es, uma ainda n\u00e3o finalizada. O objetivo dos servi\u00e7os \u00e9 consertar vazamentos e combater as perdas de \u00e1gua. Moradores do entorno dos pontos de manuten\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":60,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,8],"tags":[],"class_list":["post-7654","post","type-post","status-publish","format-standard","hentry","category-agua-e-esgoto","category-releases"],"_links":{"self":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/7654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/comments?post=7654"}],"version-history":[{"count":1,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/7654\/revisions"}],"predecessor-version":[{"id":7655,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/7654\/revisions\/7655"}],"wp:attachment":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/media?parent=7654"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/categories?post=7654"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/tags?post=7654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}