{"id":7576,"date":"2019-01-11T16:57:00","date_gmt":"2019-01-11T18:57:00","guid":{"rendered":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/?p=7576"},"modified":"2026-04-14T16:57:38","modified_gmt":"2026-04-14T19:57:38","slug":"fique-atento-semasa-informa-manutencoes-do-dia-11-01-2019","status":"publish","type":"post","link":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/2019\/01\/11\/fique-atento-semasa-informa-manutencoes-do-dia-11-01-2019\/","title":{"rendered":"Fique atento: Semasa informa manuten\u00e7\u00f5es do dia 11\/01\/2019"},"content":{"rendered":"\n<p>O Semasa informa que, das 0h \u00e0s 13h de hoje, equipes da autarquia&nbsp; precisaram realizar 2 fechamentos de \u00e1gua para manuten\u00e7\u00e3o.<\/p>\n\n\n\n<p>No dia anterior, foram realizados 3 fechamentos para interven\u00e7\u00f5es.<\/p>\n\n\n\n<p>O objetivo dos servi\u00e7os \u00e9 consertar vazamentos e combater as perdas de \u00e1gua.<\/p>\n\n\n\n<p>Moradores do entorno dos pontos de manuten\u00e7\u00e3o podem ter problemas de abastecimento.<\/p>\n\n\n\n<p><strong>Confira os endere\u00e7os e hor\u00e1rios das manuten\u00e7\u00f5es.<\/strong><strong>&nbsp;<\/strong><strong>&nbsp;<\/strong><strong>&nbsp;<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td><strong>11\/01\/2019 \u2013 Das 0h \u00e0s 13h de hoje<\/strong><\/td><td><strong>In\u00edcio<\/strong><\/td><td><strong>T\u00e9rmino<\/strong><\/td><\/tr><tr><td>Avenida Loreto (Jardim Santo Andr\u00e9)<\/td><td>12h56<\/td><td>\u2013<\/td><\/tr><tr><td>Rua dos Aliados (Santa Terezinha)<\/td><td>9h54<\/td><td>12h20<\/td><\/tr><tr><td>Rua Campos Vergueiro (Vila Humait\u00e1)<\/td><td>9h<\/td><td>10h40<\/td><\/tr><tr><td><\/td><td><\/td><td><\/td><\/tr><tr><td><strong>10\/01\/2019<\/strong><\/td><td><strong>In\u00edcio<\/strong><\/td><td><strong>T\u00e9rmino<\/strong><\/td><\/tr><tr><td>Rua Fioravanti Signorelli (Vila Palmares)<\/td><td>16h34<\/td><td>10h12 de 11\/1<\/td><\/tr><tr><td>Rua do Cruzeiro (Ass.Cruzado II-CDHU, Jardim Santo Andr\u00e9)<\/td><td>14h391<\/td><td>8h35 de 11\/1<\/td><\/tr><\/tbody><\/table><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>O Semasa informa que, das 0h \u00e0s 13h de hoje, equipes da autarquia&nbsp; precisaram realizar 2 fechamentos de \u00e1gua para manuten\u00e7\u00e3o. No dia anterior, foram realizados 3 fechamentos para interven\u00e7\u00f5es. O objetivo dos servi\u00e7os \u00e9 consertar vazamentos e combater as perdas de \u00e1gua. Moradores do entorno dos pontos de manuten\u00e7\u00e3o podem ter problemas de abastecimento. [&hellip;]<\/p>\n","protected":false},"author":60,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,8],"tags":[],"class_list":["post-7576","post","type-post","status-publish","format-standard","hentry","category-agua-e-esgoto","category-releases"],"_links":{"self":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/7576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/comments?post=7576"}],"version-history":[{"count":1,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/7576\/revisions"}],"predecessor-version":[{"id":7577,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/7576\/revisions\/7577"}],"wp:attachment":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/media?parent=7576"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/categories?post=7576"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/tags?post=7576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}