{"id":4480,"date":"2016-08-11T11:26:00","date_gmt":"2016-08-11T14:26:00","guid":{"rendered":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/?p=4480"},"modified":"2025-08-11T11:26:55","modified_gmt":"2025-08-11T14:26:55","slug":"fornecimento-de-agua-em-10-08-2016","status":"publish","type":"post","link":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/2016\/08\/11\/fornecimento-de-agua-em-10-08-2016\/","title":{"rendered":"Fornecimento de \u00e1gua em 10\/08\/2016"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Santo Andr\u00e9, 11 de agosto de 2016 \u2013 O Semasa informa que no dia 10 de agosto de 2016 (quarta-feira),&nbsp;a cidade de Santo Andr\u00e9 recebeu a seguinte quantidade m\u00e9dia de \u00e1gua, por parte da Sabesp:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>10 de agosto<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Sistema Rio Grande (Billings):<\/strong>1,16 m\u00b3\/s<\/li>\n\n\n\n<li><strong>Sistema Rio Claro:<\/strong>0,68 m\u00b3\/s<\/li>\n\n\n\n<li><strong>M\u00e9dia total:<\/strong>1,84 m\u00b3\/s<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Finais de semana e feriados:<\/strong>&nbsp;Salientamos que, em datas especiais, as informa\u00e7\u00f5es ser\u00e3o disponibilizadas e enviadas no dia \u00fatil imediatamente posterior.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Abastecimento:&nbsp;<\/strong>Dois sistemas s\u00e3o respons\u00e1veis pelo abastecimento da cidade: Rio Claro, respons\u00e1vel por 30%, e Rio Grande (Billings), respons\u00e1vel por 70%. Santo Andr\u00e9 compra 95% de sua \u00e1gua da Sabesp. O munic\u00edpio possui mais de 700 mil habitantes e recebia o necess\u00e1rio para abastecer a cidade de maneira equilibrada \u2013 cerca de 2.300 litros de \u00e1gua por segundo (2,3 m\u00b3\/s). Em julho de 2015 ficou acordado, entre Santo Andr\u00e9 e Sabesp, o envio de cerca de 1.750 litros por segundo (1,75 m\u00b3\/s) &nbsp;\u2013 por\u00e9m, &nbsp;a vaz\u00e3o n\u00e3o \u00e9 linear durante as 24 horas do dia e, nos hor\u00e1rios de maior consumo, o envio da \u00e1gua na maioria das vezes est\u00e1 abaixo do acordado. Todos os dias, o Semasa realiza manobras operacionais para manter o abastecimento dos setores em pelo menos um per\u00edodo do dia, de forma a amenizar as defici\u00eancias que tem ocorrido e tentando melhorar a regularidade do fornecimento de \u00e1gua.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Andr\u00e9, 11 de agosto de 2016 \u2013 O Semasa informa que no dia 10 de agosto de 2016 (quarta-feira),&nbsp;a cidade de Santo Andr\u00e9 recebeu a seguinte quantidade m\u00e9dia de \u00e1gua, por parte da Sabesp: 10 de agosto Finais de semana e feriados:&nbsp;Salientamos que, em datas especiais, as informa\u00e7\u00f5es ser\u00e3o disponibilizadas e enviadas no dia [&hellip;]<\/p>\n","protected":false},"author":60,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,8],"tags":[],"class_list":["post-4480","post","type-post","status-publish","format-standard","hentry","category-agua-e-esgoto","category-releases"],"_links":{"self":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/4480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/comments?post=4480"}],"version-history":[{"count":1,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/4480\/revisions"}],"predecessor-version":[{"id":4481,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/4480\/revisions\/4481"}],"wp:attachment":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/media?parent=4480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/categories?post=4480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/tags?post=4480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}