{"id":3448,"date":"2016-02-29T14:41:00","date_gmt":"2016-02-29T17:41:00","guid":{"rendered":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/?p=3448"},"modified":"2025-02-28T14:45:06","modified_gmt":"2025-02-28T17:45:06","slug":"fornecimento-de-agua-de-26-a-28-2-16","status":"publish","type":"post","link":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/2016\/02\/29\/fornecimento-de-agua-de-26-a-28-2-16\/","title":{"rendered":"Fornecimento de \u00e1gua de 26 a 28\/2\/16"},"content":{"rendered":"\n<p><strong>Santo Andr\u00e9, 29 de fevereiro de 2016 \u2013 O Semasa informa que, nos dias 26, 27 e 28 de fevereiro de 2016 (sexta-feira, s\u00e1bado e domingo), a cidade de Santo Andr\u00e9 recebeu as seguintes quantidades de \u00e1gua, por parte da Sabesp:<\/strong><\/p>\n\n\n\n<p><strong>26 de fevereiro<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Sistema Rio Grande (Billings):<\/strong>\u00a01,22 m\u00b3\/s<\/li>\n\n\n\n<li><strong>Sistema Rio Claro:<\/strong>\u00a00,64 m\u00b3\/s<\/li>\n\n\n\n<li><strong>M\u00e9dia total:<\/strong>\u00a01,86 m\u00b3\/s<\/li>\n<\/ul>\n\n\n\n<p><strong>27 de fevereiro<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Sistema Rio Grande (Billings):<\/strong>\u00a01,12 m\u00b3\/s<\/li>\n\n\n\n<li><strong>Sistema Rio Claro:<\/strong>\u00a00,82 m\u00b3\/s<\/li>\n\n\n\n<li><strong>M\u00e9dia total:<\/strong>\u00a01,95 m\u00b3\/s<\/li>\n<\/ul>\n\n\n\n<p><strong>28 de fevereiro<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Sistema Rio Grande (Billings):<\/strong>\u00a01,17 m\u00b3\/s<\/li>\n\n\n\n<li><strong>Sistema Rio Claro:<\/strong>\u00a00,77 m\u00b3\/s<\/li>\n\n\n\n<li><strong>M\u00e9dia total:<\/strong>\u00a01,94 m\u00b3\/s<\/li>\n<\/ul>\n\n\n\n<p><strong>Finais de semana e feriados:<\/strong>&nbsp;Refor\u00e7amos em datas especiais as informa\u00e7\u00f5es ser\u00e3o disponibilizadas e enviadas no dia \u00fatil imediatamente posterior.<\/p>\n\n\n\n<p><strong>Abastecimento:\u00a0<\/strong>dois sistemas s\u00e3o respons\u00e1veis pelo abastecimento da cidade: Rio Claro, respons\u00e1vel por 30%, e Rio Grande (Billings), respons\u00e1vel por 70%.\u00a0Santo Andr\u00e9 compra 95% de sua \u00e1gua da Sabesp. O munic\u00edpio possui mais de 700 mil habitantes e, anteriormente a crise h\u00eddrica, recebia o necess\u00e1rio para abastecer a cidade de maneira equilibrada \u2013 cerca de 2 mil litros de \u00e1gua por segundo (2,0 m\u00b3\/s). Desde o agravamento da situa\u00e7\u00e3o em toda a regi\u00e3o metropolitana, foi acordado, entre Santo Andr\u00e9 e Sabesp, o envio de cerca de 1.750 litros por segundo (1,75 m\u00b3\/s) \u2013 26% a menos. Todos os dias, o Semasa realiza manobras operacionais para manter o abastecimento dos setores em pelo menos um per\u00edodo do dia, de forma a amenizar as defici\u00eancias que tem ocorrido e tentando melhorar a regularidade do fornecimento de \u00e1gua.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Andr\u00e9, 29 de fevereiro de 2016 \u2013 O Semasa informa que, nos dias 26, 27 e 28 de fevereiro de 2016 (sexta-feira, s\u00e1bado e domingo), a cidade de Santo Andr\u00e9 recebeu as seguintes quantidades de \u00e1gua, por parte da Sabesp: 26 de fevereiro 27 de fevereiro 28 de fevereiro Finais de semana e feriados:&nbsp;Refor\u00e7amos [&hellip;]<\/p>\n","protected":false},"author":60,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,8],"tags":[],"class_list":["post-3448","post","type-post","status-publish","format-standard","hentry","category-agua-e-esgoto","category-releases"],"_links":{"self":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/3448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/comments?post=3448"}],"version-history":[{"count":2,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/3448\/revisions"}],"predecessor-version":[{"id":3450,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/3448\/revisions\/3450"}],"wp:attachment":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/media?parent=3448"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/categories?post=3448"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/tags?post=3448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}