{"id":3417,"date":"2025-02-14T08:55:23","date_gmt":"2025-02-14T11:55:23","guid":{"rendered":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/?p=3417"},"modified":"2025-02-17T08:55:46","modified_gmt":"2025-02-17T11:55:46","slug":"moeda-verde-chega-a-31a-comunidade-com-foco-em-reciclagem-e-servicos-de-saude","status":"publish","type":"post","link":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/2025\/02\/14\/moeda-verde-chega-a-31a-comunidade-com-foco-em-reciclagem-e-servicos-de-saude\/","title":{"rendered":"Moeda Verde chega \u00e0 31\u00aa comunidade com foco em reciclagem e servi\u00e7os de sa\u00fade"},"content":{"rendered":"\n<p><em>Programa andreense que troca res\u00edduo recicl\u00e1vel por hortifr\u00fati iniciou parceria com o caminh\u00e3o itinerante do Sa\u00fade em Movimento<\/em><\/p>\n\n\n\n<p>Santo Andr\u00e9, 14 de fevereiro de 2025 \u2013 Reciclagem que alimenta \u00e9 o mote do programa Moeda Verde, mas, a partir desta sexta-feira (14), a iniciativa ganha mais uma importante conquista: a inclus\u00e3o de servi\u00e7os de sa\u00fade em algumas edi\u00e7\u00f5es. Durante a estreia da a\u00e7\u00e3o nos conjuntos Prestes Maia e Gon\u00e7alo Zarco, na Vila Aquilino, em Santo Andr\u00e9, os participantes trocaram materiais recicl\u00e1veis por hortifr\u00fati e foram beneficiados com orienta\u00e7\u00e3o e atendimento m\u00e9dico.<\/p>\n\n\n\n<p>A novidade est\u00e1 na parceria com o programa Sa\u00fade em Movimento, que traz um caminh\u00e3o itinerante equipado com dois consult\u00f3rios que oferecem, com o apoio de profissionais das unidades de sa\u00fade, v\u00e1rios tipos de aferi\u00e7\u00f5es, vacinas, testes r\u00e1pidos, dentre outros servi\u00e7os.<\/p>\n\n\n\n<p>\u201cO Moeda Verde \u00e9 uma importante pol\u00edtica p\u00fablica que traz seguran\u00e7a alimentar, educa\u00e7\u00e3o ambiental, incentivo \u00e0 coleta seletiva e gera\u00e7\u00e3o de trabalho e renda para as pessoas que vivem da reciclagem nas cooperativas. Agora, o nosso foco est\u00e1 em aproximar ainda mais os mun\u00edcipes dos servi\u00e7os de sa\u00fade para que possamos prevenir doen\u00e7as e orient\u00e1-los a ter uma vida mais saud\u00e1vel\u201d, explica o prefeito Gilvan Junior.<\/p>\n\n\n\n<p>A aposentada Maria das Neves Ferreira, de 68 anos, moradora do Conjunto Habitacional Prestes Maia, foi para casa com felicidade em dobro:&nbsp; uma por ter a oportunidade de trocar recicl\u00e1veis por frutas, legumes e uma verdura e outra por receber orienta\u00e7\u00f5es m\u00e9dicas.<\/p>\n\n\n\n<p>\u201cEsta a\u00e7\u00e3o do Moeda Verde \u00e9 boa porque melhora a conserva\u00e7\u00e3o da comunidade. As pessoas deixam de jogar lixo e enxergam que ele tem valor. J\u00e1 o Sa\u00fade em Movimento ajudar\u00e1 muita gente daqui que n\u00e3o consegue se deslocar para uma UBS (Unidade B\u00e1sica de Sa\u00fade)\u201d, explica. Ela aproveitou para medir a press\u00e3o \u2013 que estava um pouco alta \u2013 e a glicemia. Toda sorridente, avisou que \u201cj\u00e1 vai fazer uma saladinha de alface para baixar a press\u00e3o\u201d.<\/p>\n\n\n\n<p>Durante a estreia do Moeda Verde nos conjuntos Prestes Maia e Gon\u00e7alo Zarco, a 31\u00aa comunidade beneficiada pela a\u00e7\u00e3o, o programa Sa\u00fade em Movimento ofereceu orienta\u00e7\u00f5es e avalia\u00e7\u00f5es f\u00edsica e nutricional, auriculoterapia, avalia\u00e7\u00e3o bucal, atendimento com m\u00e9dico generalista, al\u00e9m de aferi\u00e7\u00f5es de glicemia e press\u00e3o arterial, exame de bioimped\u00e2ncia (an\u00e1lise da composi\u00e7\u00e3o corporal, como massa muscular e gordura), orienta\u00e7\u00f5es sobre reutiliza\u00e7\u00e3o de alimentos, dentre outros.<\/p>\n\n\n\n<p><strong>Pol\u00edtica p\u00fablica transversal \u2013<\/strong> O programa Moeda Verde \u00e9 levado para comunidades de Santo Andr\u00e9 que s\u00e3o vulner\u00e1veis a v\u00e1rios problemas socioambientais, como descarte irregular de res\u00edduos e inseguran\u00e7a alimentar.<\/p>\n\n\n\n<p>\u201cS\u00e3o nesses locais que a Prefeitura e o Semasa (Servi\u00e7o Municipal de Saneamento Ambiental de Santo Andr\u00e9) t\u00eam entrado. Hoje, chegamos a 60% das comunidades que possuem domic\u00edlios com renda de at\u00e9&nbsp; \u00bd sal\u00e1rio m\u00ednimo e a nossa proje\u00e7\u00e3o \u00e9 de estar em 100% dessas \u00e1reas vulner\u00e1veis\u201d, explica o secret\u00e1rio de Meio Ambiente e Mudan\u00e7as Clim\u00e1ticas, Edinilson Ferreira dos Santos.<\/p>\n\n\n\n<p><strong>Moeda Pet \u2013<\/strong> Desde fevereiro deste ano, todas as comunidades do munic\u00edpio onde ocorre a realiza\u00e7\u00e3o do programa Moeda Verde agora tamb\u00e9m s\u00e3o beneficiadas pelo Moeda Pet, que troca garrafas PET por ra\u00e7\u00e3o para c\u00e3es e gatos.<\/p>\n\n\n\n<p>Com essas duas pol\u00edticas p\u00fablicas integradas, a cidade oferece alimenta\u00e7\u00e3o saud\u00e1vel tanto para as pessoas quanto para os animais, contribuindo, paralelamente, no aumento da reciclagem e do tempo de opera\u00e7\u00e3o do Aterro Sanit\u00e1rio Municipal.<\/p>\n\n\n\n<p>A secret\u00e1ria de Assist\u00eancia Social e presidente do Fundo Social de Solidariedade, Ana Claudia de Fabris, que tamb\u00e9m marcou presen\u00e7a na estreia dos programas Moeda Verde e Moeda Pet nos conjuntos Prestes Maia e Gon\u00e7alo Zarco, chamou a aten\u00e7\u00e3o para o protagonismo da popula\u00e7\u00e3o. \u201cO Moeda Verde e Moeda Pet foram feitos para voc\u00eas. Tragam os seus materiais recicl\u00e1veis e as suas garrafas PET porque o sucesso dessas a\u00e7\u00f5es depende muito de voc\u00eas\u201d, explicou. A programa\u00e7\u00e3o completa dos dois programas, com informa\u00e7\u00f5es sobre locais e hor\u00e1rios das trocas, pode ser consultada em <a href=\"http:\/\/www.semasa.sp.gov.br\/moedaverde\">www.semasa.sp.gov.br\/moedaverde<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Programa andreense que troca res\u00edduo recicl\u00e1vel por hortifr\u00fati iniciou parceria com o caminh\u00e3o itinerante do Sa\u00fade em Movimento Santo Andr\u00e9, 14 de fevereiro de 2025 \u2013 Reciclagem que alimenta \u00e9 o mote do programa Moeda Verde, mas, a partir desta sexta-feira (14), a iniciativa ganha mais uma importante conquista: a inclus\u00e3o de servi\u00e7os de sa\u00fade [&hellip;]<\/p>\n","protected":false},"author":28,"featured_media":3418,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,5],"tags":[],"class_list":["post-3417","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-releases","category-residuos-solidos"],"_links":{"self":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/3417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/comments?post=3417"}],"version-history":[{"count":1,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/3417\/revisions"}],"predecessor-version":[{"id":3419,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/3417\/revisions\/3419"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/media\/3418"}],"wp:attachment":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/media?parent=3417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/categories?post=3417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/tags?post=3417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}