{"id":3344,"date":"2016-02-17T11:28:00","date_gmt":"2016-02-17T13:28:00","guid":{"rendered":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/?p=3344"},"modified":"2025-02-06T11:28:39","modified_gmt":"2025-02-06T14:28:39","slug":"jd-mirante-passa-a-ter-coleta-de-residuos-umidos-porta-a-porta-em-100-de-suas-residencias","status":"publish","type":"post","link":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/2016\/02\/17\/jd-mirante-passa-a-ter-coleta-de-residuos-umidos-porta-a-porta-em-100-de-suas-residencias\/","title":{"rendered":"Jd. Mirante passa a ter coleta de res\u00edduos \u00famidos porta a porta em 100% de suas resid\u00eancias"},"content":{"rendered":"\n<p><strong>Santo Andr\u00e9, 17 de fevereiro de 2016 \u2013 O Jardim do Mirante, novo bairro de Santo Andr\u00e9 (pr\u00f3ximo ao Jardim Carla, na estrada Guaraciaba), conta desde ontem com a coleta de res\u00edduos \u00famidos em 100% de suas ruas e travessas.<\/strong><\/p>\n\n\n\n<p>O local era atendido por um ve\u00edculo coletor compactador de grande porte e isso impedia a passagem do caminh\u00e3o em algumas das travessas, por serem estreitas. Desde ontem, o bairro conta tamb\u00e9m com um ve\u00edculo coletor de menor porte, para dar suporte ao trabalho nas vias mais estreitas.<\/p>\n\n\n\n<p>O objetivo \u00e9 eliminar todos os pontos irregulares de ac\u00famulo de res\u00edduos, gerados e mantidos por moradores que n\u00e3o contavam com a coleta porta a porta. Essa inclus\u00e3o melhorar\u00e1 a qualidade de vida de todos ao redor. Ao todo, s\u00e3o 25 vielas, al\u00e9m das vias comuns, que passaram a contar o servi\u00e7o.<\/p>\n\n\n\n<p>Na \u00faltima segunda-feira, equipes do Departamento de Res\u00edduos S\u00f3lidos e lideran\u00e7as locais se reuniram no bairro para promover orienta\u00e7\u00e3o&nbsp;a mais das 400 fam\u00edlias moradoras. Foi definido que, inicialmente, a coleta de \u00famidos ser\u00e1 realizada todas as ter\u00e7as-feiras, quintas e s\u00e1bados, a partir das 7h. Em data a ser definida,&nbsp;ser\u00e1 implantada a coleta&nbsp;de secos, \u00e0s segundas-feiras.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Andr\u00e9, 17 de fevereiro de 2016 \u2013 O Jardim do Mirante, novo bairro de Santo Andr\u00e9 (pr\u00f3ximo ao Jardim Carla, na estrada Guaraciaba), conta desde ontem com a coleta de res\u00edduos \u00famidos em 100% de suas ruas e travessas. O local era atendido por um ve\u00edculo coletor compactador de grande porte e isso impedia [&hellip;]<\/p>\n","protected":false},"author":60,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,5],"tags":[],"class_list":["post-3344","post","type-post","status-publish","format-standard","hentry","category-releases","category-residuos-solidos"],"_links":{"self":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/3344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/comments?post=3344"}],"version-history":[{"count":1,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/3344\/revisions"}],"predecessor-version":[{"id":3345,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/3344\/revisions\/3345"}],"wp:attachment":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/media?parent=3344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/categories?post=3344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/tags?post=3344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}