{"id":3224,"date":"2015-12-22T14:44:00","date_gmt":"2015-12-22T16:44:00","guid":{"rendered":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/?p=3224"},"modified":"2025-02-03T14:45:00","modified_gmt":"2025-02-03T17:45:00","slug":"fornecimento-de-agua-em-21-12-2015","status":"publish","type":"post","link":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/2015\/12\/22\/fornecimento-de-agua-em-21-12-2015\/","title":{"rendered":"Fornecimento de \u00e1gua em 21\/12\/2015"},"content":{"rendered":"\n<p><strong>Santo Andr\u00e9, 22 de dezembro de 2015 \u2013 O Semasa informa que em 21 de dezembro de 2015 (segunda-feira), a m\u00e9dia da \u00e1gua enviada pela Sabesp \u00e0 cidade de Santo Andr\u00e9 foi de 1.760 litros por segundo.&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>21 de dezembro<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Sistema Rio Grande (Billings):<\/strong>\u00a01,18 \u00a0m\u00b3\/s<\/li>\n\n\n\n<li><strong>Sistema Rio Claro:<\/strong>\u00a00,58 \u00a0m\u00b3\/s<\/li>\n\n\n\n<li><strong>M\u00e9dia total:<\/strong>\u00a0 \u00a01,76 m\u00b3\/s<\/li>\n<\/ul>\n\n\n\n<p><strong>Abastecimento:&nbsp;<\/strong>dois sistemas s\u00e3o respons\u00e1veis pelo abastecimento da cidade: Rio Claro, respons\u00e1vel por 30%, e Rio Grande (Billings), respons\u00e1vel por 70%.&nbsp;Santo Andr\u00e9 compra 95% de sua \u00e1gua da Sabesp. O munic\u00edpio possui mais de 700 mil habitantes e, anteriormente a crise h\u00eddrica, recebia o necess\u00e1rio para abastecer a cidade de maneira equilibrada \u2013 cerca de 2.370 mil litros de \u00e1gua por segundo (2,37 m\u00b3\/s). Desde o agravamento da situa\u00e7\u00e3o em toda a regi\u00e3o metropolitana, foi acordado, entre Santo Andr\u00e9 e Sabesp, o envio de cerca de 1.750 litros por segundo (1,75 m\u00b3\/s) \u2013 26% a menos. Todos os dias, o Semasa realiza manobras operacionais para manter o abastecimento dos setores em pelo menos um per\u00edodo do dia, de forma a amenizar as defici\u00eancias que tem ocorrido e tentando melhorar a regularidade do fornecimento de \u00e1gua.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Andr\u00e9, 22 de dezembro de 2015 \u2013 O Semasa informa que em 21 de dezembro de 2015 (segunda-feira), a m\u00e9dia da \u00e1gua enviada pela Sabesp \u00e0 cidade de Santo Andr\u00e9 foi de 1.760 litros por segundo.&nbsp; 21 de dezembro Abastecimento:&nbsp;dois sistemas s\u00e3o respons\u00e1veis pelo abastecimento da cidade: Rio Claro, respons\u00e1vel por 30%, e Rio [&hellip;]<\/p>\n","protected":false},"author":60,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,8],"tags":[],"class_list":["post-3224","post","type-post","status-publish","format-standard","hentry","category-agua-e-esgoto","category-releases"],"_links":{"self":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/3224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/comments?post=3224"}],"version-history":[{"count":1,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/3224\/revisions"}],"predecessor-version":[{"id":3225,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/3224\/revisions\/3225"}],"wp:attachment":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/media?parent=3224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/categories?post=3224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/tags?post=3224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}