{"id":3099,"date":"2015-10-20T15:14:00","date_gmt":"2015-10-20T17:14:00","guid":{"rendered":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/?p=3099"},"modified":"2025-01-28T15:14:38","modified_gmt":"2025-01-28T18:14:38","slug":"educacao-ambiental-do-semasa-participa-de-evento-da-jornada-gandhi-neste-sabado-24","status":"publish","type":"post","link":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/2015\/10\/20\/educacao-ambiental-do-semasa-participa-de-evento-da-jornada-gandhi-neste-sabado-24\/","title":{"rendered":"Educa\u00e7\u00e3o Ambiental do Semasa participa de evento da Jornada Gandhi neste s\u00e1bado (24)"},"content":{"rendered":"\n<p><strong>Santo Andr\u00e9, 20 de outubro de 2015 \u2013 A Prefeitura de Santo Andr\u00e9 realiza no pr\u00f3ximo s\u00e1bado (24) a pen\u00faltima atividade da programa\u00e7\u00e3o comemorativa da Jornada Gandhi do munic\u00edpio. O evento \u2018A\u00e7\u00f5es que Transformam\u2019 vai acontecer no Complexo Esportivo Pedro Dell\u2019Antonia, das 9h \u00e0s 13h, e trar\u00e1 atividades para a toda a fam\u00edlia.<\/strong><\/p>\n\n\n\n<p>A Jornada Gandhi visa celebrar e divulgar o Dia Internacional da N\u00e3o Viol\u00eancia, comemorado em 2\/10. Essa data marca tamb\u00e9m o nascimento do l\u00edder hindu Mahatma Gandhi \u2013 pol\u00edtico e l\u00edder no movimento de independ\u00eancia da \u00cdndia e considerado o grande ativista da N\u00e3o Viol\u00eancia.<\/p>\n\n\n\n<p>A Educa\u00e7\u00e3o Ambiental do Semasa estar\u00e1 presente no evento e realizar\u00e1 algumas oficinas de reaproveitamento de materiais. A ideia \u00e9 sensibilizar os participantes para os cuidados com a gera\u00e7\u00e3o de res\u00edduos, al\u00e9m demonstrar como \u00e9 poss\u00edvel transformar objetos que seriam descartados em brinquedos ou decora\u00e7\u00e3o.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/www.semasa.sp.gov.br\/wp-content\/uploads\/2015\/10\/DSC_0091.jpg\"><img decoding=\"async\" src=\"https:\/\/www.semasa.sp.gov.br\/wp-content\/uploads\/2015\/10\/DSC_0091-300x199.jpg\" alt=\"DSC_0091\" class=\"wp-image-11820\" \/><\/a><\/figure><\/div>\n\n\n<p>Ser\u00e3o oferecidas oficinas de origami para os adultos, na qual ser\u00e3o produzidas flores a partir de folhas de revistas. Para a crian\u00e7ada, a equipe de educa\u00e7\u00e3o ambiental mostrar\u00e1 como fazer bonecos ecol\u00f3gicos com reaproveitamento de copos pl\u00e1sticos. Tamb\u00e9m ser\u00e1 oferecida a oficina de confec\u00e7\u00e3o de Minions, os personagens amarelinhos do filme \u201cMeu Malvado Favorito\u201d, que ganhar\u00e3o vida a partir da reutiliza\u00e7\u00e3o de rolos e sobras de papel.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><a href=\"https:\/\/www.semasa.sp.gov.br\/wp-content\/uploads\/2015\/10\/DSC06424.jpg\"><img decoding=\"async\" src=\"https:\/\/www.semasa.sp.gov.br\/wp-content\/uploads\/2015\/10\/DSC06424-300x225.jpg\" alt=\"DSC06424\" class=\"wp-image-11821\" \/><\/a><\/figure><\/div>\n\n\n<p><strong>Deprecated<\/strong>: str_contains(): Passing null to parameter #1 ($haystack) of type string is deprecated in&nbsp;<strong>\/var\/www\/semasa.sp.gov.br\/wp-includes\/shortcodes.php<\/strong>&nbsp;on line&nbsp;<strong>246<\/strong><\/p>\n\n\n\n<p><strong>Deprecated<\/strong>: preg_split(): Passing null to parameter #2 ($subject) of type string is deprecated in&nbsp;<strong>\/var\/www\/semasa.sp.gov.br\/wp-includes\/formatting.php<\/strong>&nbsp;on line&nbsp;<strong>616<\/strong><\/p>\n\n\n\n<p><strong>Deprecated<\/strong>: preg_match(): Passing null to parameter #2 ($subject) of type string is deprecated in&nbsp;<strong>\/var\/www\/semasa.sp.gov.br\/wp-includes\/class-wp-embed.php<\/strong>&nbsp;on line&nbsp;<strong>446<\/strong><\/p>\n\n\n\n<p><strong>Deprecated<\/strong>: str_replace(): Passing null to parameter #3 ($subject) of type array|string is deprecated in&nbsp;<strong>\/var\/www\/semasa.sp.gov.br\/wp-includes\/class-wp-embed.php<\/strong>&nbsp;on line&nbsp;<strong>454<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Andr\u00e9, 20 de outubro de 2015 \u2013 A Prefeitura de Santo Andr\u00e9 realiza no pr\u00f3ximo s\u00e1bado (24) a pen\u00faltima atividade da programa\u00e7\u00e3o comemorativa da Jornada Gandhi do munic\u00edpio. O evento \u2018A\u00e7\u00f5es que Transformam\u2019 vai acontecer no Complexo Esportivo Pedro Dell\u2019Antonia, das 9h \u00e0s 13h, e trar\u00e1 atividades para a toda a fam\u00edlia. A Jornada [&hellip;]<\/p>\n","protected":false},"author":60,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,8],"tags":[],"class_list":["post-3099","post","type-post","status-publish","format-standard","hentry","category-educacao-ambiental","category-releases"],"_links":{"self":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/3099","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/comments?post=3099"}],"version-history":[{"count":1,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/3099\/revisions"}],"predecessor-version":[{"id":3100,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/3099\/revisions\/3100"}],"wp:attachment":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/media?parent=3099"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/categories?post=3099"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/tags?post=3099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}