{"id":3018,"date":"2015-08-03T15:09:00","date_gmt":"2015-08-03T18:09:00","guid":{"rendered":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/?p=3018"},"modified":"2025-01-21T15:10:32","modified_gmt":"2025-01-21T18:10:32","slug":"semasa-retoma-o-programa-de-coleta-comunitaria-nos-nucleos-habitacionais-de-s-andre","status":"publish","type":"post","link":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/2015\/08\/03\/semasa-retoma-o-programa-de-coleta-comunitaria-nos-nucleos-habitacionais-de-s-andre\/","title":{"rendered":"Semasa retoma o Programa de Coleta Comunit\u00e1ria nos n\u00facleos habitacionais de S. Andr\u00e9"},"content":{"rendered":"\n<p><strong>Santo Andr\u00e9, 03 de agosto de 2015 \u2013 O Semasa (Servi\u00e7o Municipal de Saneamento Ambiental de Santo Andr\u00e9) iniciou neste \u00faltimo s\u00e1bado (01\/08) a retomada da figura do coletor comunit\u00e1rio em n\u00facleos habitacionais. O local escolhido foi o n\u00facleo Esp\u00edrito Santo, uma \u00e1rea de assentamento habitacional informal, que possui vielas de dif\u00edcil acesso, que impedem a passagem do caminh\u00e3o de coleta.<\/strong><\/p>\n\n\n\n<p>O n\u00facleo Esp\u00edrito Santo foi o primeiro a receber os servi\u00e7os, pois al\u00e9m das ruas estreitas e \u00edngremes, possui um grande ponto de descarte irregular de res\u00edduos. O coletor comunit\u00e1rio \u00e9 um profissional contratado pela empresa prestadora de servi\u00e7os de coleta de res\u00edduos na cidade e prioritariamente morador de assentamento prec\u00e1rio. Ele tem como tarefa coletar os res\u00edduos porta a porta das vielas de dif\u00edcil acesso e acondicion\u00e1-los na via onde \u00e9 poss\u00edvel a passagem do caminh\u00e3o.<\/p>\n\n\n\n<p>A frequ\u00eancia de coleta de res\u00edduos secos e \u00famidos ser\u00e1 a mesma do bairro onde est\u00e1 inserido o assentamento prec\u00e1rio.<\/p>\n\n\n\n<p>O n\u00facleo Espirito Santo passa por processo de urbaniza\u00e7\u00e3o pela Prefeitura de Santo Andr\u00e9, que prev\u00ea a abertura e alargamento de algumas vias, permitindo num futuro pr\u00f3ximo o acesso do caminh\u00e3o de coleta.<\/p>\n\n\n\n<p>At\u00e9 o fim do ano, o Semasa pretende levar o servi\u00e7o de coleta comunit\u00e1ria para outros 27 n\u00facleos habitacionais do munic\u00edpio. O servi\u00e7o vai permitir a melhora da qualidade ambiental destes assentamentos, pois a disposi\u00e7\u00e3o irregular de lixo, entre outros problemas, ocasiona a prolifera\u00e7\u00e3o de vetores.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Andr\u00e9, 03 de agosto de 2015 \u2013 O Semasa (Servi\u00e7o Municipal de Saneamento Ambiental de Santo Andr\u00e9) iniciou neste \u00faltimo s\u00e1bado (01\/08) a retomada da figura do coletor comunit\u00e1rio em n\u00facleos habitacionais. O local escolhido foi o n\u00facleo Esp\u00edrito Santo, uma \u00e1rea de assentamento habitacional informal, que possui vielas de dif\u00edcil acesso, que impedem [&hellip;]<\/p>\n","protected":false},"author":60,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,5],"tags":[],"class_list":["post-3018","post","type-post","status-publish","format-standard","hentry","category-releases","category-residuos-solidos"],"_links":{"self":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/3018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/comments?post=3018"}],"version-history":[{"count":1,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/3018\/revisions"}],"predecessor-version":[{"id":3019,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/3018\/revisions\/3019"}],"wp:attachment":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/media?parent=3018"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/categories?post=3018"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/tags?post=3018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}