{"id":2955,"date":"2015-06-08T15:50:00","date_gmt":"2015-06-08T18:50:00","guid":{"rendered":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/?p=2955"},"modified":"2025-01-16T15:50:38","modified_gmt":"2025-01-16T18:50:38","slug":"piscinao-sta-terezinha-ganha-camera-de-monitoramento","status":"publish","type":"post","link":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/2015\/06\/08\/piscinao-sta-terezinha-ganha-camera-de-monitoramento\/","title":{"rendered":"Piscin\u00e3o Sta. Terezinha ganha c\u00e2mera de monitoramento"},"content":{"rendered":"\n<p><strong>Santo Andr\u00e9, 08 de junho de 2015 \u2013 O Semasa (Servi\u00e7o Municipal de Saneamento Ambiental de Santo Andr\u00e9) disponibiliza, a partir desta segunda-feira (08), uma nova c\u00e2mera de monitoramento ao vivo em seu site. O equipamento, instalado na avenida dos Estados, na altura da Craisa, vai permitir verificar o funcionamento do Piscin\u00e3o Santa Terezinha e acompanhar o n\u00edvel do rio Tamanduate\u00ed.<\/strong><\/p>\n\n\n\n<p>Com a nova c\u00e2mera, o Semasa passa a contar com sete videomonitoramentos. No site, j\u00e1 era poss\u00edvel visualizar o rio Tamanduate\u00ed (na altura da Rhodia e da avenida Sorocaba), os c\u00f3rregos Guarar\u00e1, Meninos, Guaixaya e o piscin\u00e3o Vila Am\u00e9rica.<br>Ainda este ano, o Semasa pretende instalar e deixar em funcionamento as c\u00e2meras no c\u00f3rrego Tijuco Preto (na avenida Capuava), no c\u00f3rrego Cassaquera (na altura da avenida Fernando Costa) e na Vila Palmares (entre as ruas Sim\u00e3o de Lima e Lauro Gomes), contemplando um segundo ponto do C\u00f3rrego dos Meninos.<\/p>\n\n\n\n<p>O monitoramento de rios, c\u00f3rregos e piscin\u00f5es \u00e9 parte fundamental do trabalho das equipes de Drenagem e Defesa Civil da autarquia. Por meio das c\u00e2meras \u00e9 poss\u00edvel verificar as condi\u00e7\u00f5es vi\u00e1rias e os n\u00edveis dos cursos d\u2019\u00e1gua, planejando a\u00e7\u00f5es em casos de poss\u00edveis inunda\u00e7\u00f5es.<\/p>\n\n\n\n<p>O link, que j\u00e1 pode ser acessado na home do site, apresenta as imagens destes locais atualizadas a cada dez segundos, com altern\u00e2ncia de visualiza\u00e7\u00e3o das c\u00e2meras em alguns momentos. Os motoristas podem acessar o conte\u00fado tamb\u00e9m de celulares e smartphones e saber a real condi\u00e7\u00e3o destas vias, evitando assim caminhos que possam ter sido atingidos por enchentes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Andr\u00e9, 08 de junho de 2015 \u2013 O Semasa (Servi\u00e7o Municipal de Saneamento Ambiental de Santo Andr\u00e9) disponibiliza, a partir desta segunda-feira (08), uma nova c\u00e2mera de monitoramento ao vivo em seu site. O equipamento, instalado na avenida dos Estados, na altura da Craisa, vai permitir verificar o funcionamento do Piscin\u00e3o Santa Terezinha e [&hellip;]<\/p>\n","protected":false},"author":60,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,8],"tags":[],"class_list":["post-2955","post","type-post","status-publish","format-standard","hentry","category-defesa-civil","category-releases"],"_links":{"self":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/2955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/comments?post=2955"}],"version-history":[{"count":1,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/2955\/revisions"}],"predecessor-version":[{"id":2956,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/2955\/revisions\/2956"}],"wp:attachment":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/media?parent=2955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/categories?post=2955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/tags?post=2955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}