{"id":2905,"date":"2015-04-14T15:12:00","date_gmt":"2015-04-14T18:12:00","guid":{"rendered":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/?p=2905"},"modified":"2025-01-16T15:13:00","modified_gmt":"2025-01-16T18:13:00","slug":"central-de-triagem-ja-registra-aumento-na-producao","status":"publish","type":"post","link":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/2015\/04\/14\/central-de-triagem-ja-registra-aumento-na-producao\/","title":{"rendered":"Central de Triagem j\u00e1 registra aumento na produ\u00e7\u00e3o"},"content":{"rendered":"\n<p><strong>Santo Andr\u00e9, 14 de abril de 2015 \u2013 A Central de Triagem de Res\u00edduos Recicl\u00e1veis \u2013 Unidade S\u00e3o Jorge, que come\u00e7ou a operar em fevereiro, j\u00e1 apresenta resultados positivos. Em apenas dois meses, o \u00edndice de aproveitamento do material triado pelas duas cooperativas parceiras de Santo Andr\u00e9 \u2013 Cidade Limpa e Coopcicla \u2013 aumentou 50%. Antes, 15 toneladas por dia eram reaproveitas e, atualmente, este volume chega a 21 toneladas.<\/strong><\/p>\n\n\n\n<p>A entrega da Central de Triagem foi um importante passo do Semasa no sentido de ampliar a coleta seletiva em Santo Andr\u00e9. Sem a reestrutura\u00e7\u00e3o do espa\u00e7o de trabalho das cooperativas de recicladores n\u00e3o seria poss\u00edvel lan\u00e7ar uma campanha para ampliar a coleta seletiva junto aos moradores da cidade.<\/p>\n\n\n\n<p>\u201cAgora temos condi\u00e7\u00f5es de processar todo o material que chega para as cooperativas de forma adequada\u201d, diz o superintendente do Semasa, Sebasti\u00e3o Ney Vaz Junior.<\/p>\n\n\n\n<p>Formada por dois galp\u00f5es, cada um administrado por uma cooperativa, a Central \u00e9 equipada com esteiras elevadas, prensas, balan\u00e7as eletr\u00f4nicas, empilhadeiras e carrinhos para o transporte de res\u00edduos. O espa\u00e7o tamb\u00e9m permite a amplia\u00e7\u00e3o do n\u00famero de cooperados e o trabalho em dois turnos. Antes, eram 56 recicladores e hoje este n\u00famero j\u00e1 chega aos 67, com potencial para chegar 160. O investimento foi cerca de R$ 2 milh\u00f5es.<\/p>\n\n\n\n<p><strong>Melhor forma\u00e7\u00e3o<\/strong>&nbsp;\u2013 Al\u00e9m da reestrutua\u00e7\u00e3o f\u00edsica, os cooperados tamb\u00e9m est\u00e3o recebendo treinamento mais adequado para o trabalho no local. S\u00e3o oficinas sobre cooperativismo, produtividade, organiza\u00e7\u00e3o e higiene no local de trabalho, entre outras ministradas em parcerias com a Cooperativa Central de Catadores e Catadoras de Material Recicl\u00e1vel do Grande ABC (Coopcent), o Departamento de Economia Solid\u00e1ria da Prefeitura e a Vigil\u00e2ncia Sanit\u00e1ria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Andr\u00e9, 14 de abril de 2015 \u2013 A Central de Triagem de Res\u00edduos Recicl\u00e1veis \u2013 Unidade S\u00e3o Jorge, que come\u00e7ou a operar em fevereiro, j\u00e1 apresenta resultados positivos. Em apenas dois meses, o \u00edndice de aproveitamento do material triado pelas duas cooperativas parceiras de Santo Andr\u00e9 \u2013 Cidade Limpa e Coopcicla \u2013 aumentou 50%. [&hellip;]<\/p>\n","protected":false},"author":60,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,5],"tags":[],"class_list":["post-2905","post","type-post","status-publish","format-standard","hentry","category-releases","category-residuos-solidos"],"_links":{"self":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/2905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/comments?post=2905"}],"version-history":[{"count":1,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/2905\/revisions"}],"predecessor-version":[{"id":2906,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/2905\/revisions\/2906"}],"wp:attachment":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/media?parent=2905"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/categories?post=2905"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/tags?post=2905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}