{"id":2566,"date":"2014-03-18T15:29:00","date_gmt":"2014-03-18T18:29:00","guid":{"rendered":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/?p=2566"},"modified":"2025-01-08T15:29:59","modified_gmt":"2025-01-08T18:29:59","slug":"semasa-inicia-setima-turma-do-curso-de-educacao-ambiental-para-a-melhor-idade","status":"publish","type":"post","link":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/2014\/03\/18\/semasa-inicia-setima-turma-do-curso-de-educacao-ambiental-para-a-melhor-idade\/","title":{"rendered":"Semasa inicia s\u00e9tima turma do curso de educa\u00e7\u00e3o ambiental para a melhor idade"},"content":{"rendered":"\n<p><em>Resgate hist\u00f3rico visa mostrar a transforma\u00e7\u00e3o da paisagem urbana<\/em><\/p>\n\n\n\n<p><strong>Inserir a popula\u00e7\u00e3o da terceira idade de Santo Andr\u00e9 aos conceitos de preserva\u00e7\u00e3o do meio ambiente urbano e promover o resgate hist\u00f3rico do meio em que vivem \u00e9 o objetivo do curso de educa\u00e7\u00e3o ambiental para idosos promovido pelo Semasa (Servi\u00e7o Municipal de Saneamento Ambiental de Santo Andr\u00e9). Em sua s\u00e9tima edi\u00e7\u00e3o, que teve in\u00edcio em 12\/03, o programa conta com a participa\u00e7\u00e3o do Grupo Reciprocidade do Parque Novo Orat\u00f3rio, que integra o CRISA (Centro de Refer\u00eancia do Idoso de Santo Andr\u00e9).<\/strong><\/p>\n\n\n\n<p>Ao todo, ser\u00e3o 13 encontros realizados que se estendem at\u00e9 o final da primeira quinzena de maio. A encarregada de extens\u00e3o ambiental da autarquia, Cleonice de Almeida Pinto, explica que o programa conta com conte\u00fado te\u00f3rico e pr\u00e1tico. \u201cO grupo ter\u00e1 a oportunidade de conhecer os equipamentos de educa\u00e7\u00e3o ambiental do munic\u00edpio, participar de din\u00e2micas e tamb\u00e9m de palestras informativas.&nbsp; A principal finalidade \u00e9 compartilhar, informar e sensibilizar o idoso quanto os conceitos socioambientais relevantes na comunidade\u201d.<\/p>\n\n\n\n<p><strong>O programa<\/strong>&nbsp;\u2013 O curso de educa\u00e7\u00e3o ambiental para a melhor idade teve in\u00edcio em 2010, e at\u00e9 o momento o Semasa j\u00e1 capacitou cinco grupos do CRISA e um grupo da Faculdade da Terceira Idade da Funda\u00e7\u00e3o Santo Andr\u00e9.<\/p>\n\n\n\n<p>O programa \u00e9 realizado em parceria com a Secretaria de Inclus\u00e3o e Assist\u00eancia Social e com a Secretaria de Cultura e Turismo, por meio do Museu de Santo Andr\u00e9. Este \u00faltimo \u00e9 respons\u00e1vel por fornecer imagens de seu acervo, possibilitando que os grupos possam perceber as transforma\u00e7\u00f5es nas paisagens de suas comunidades.<\/p>\n\n\n\n<p>Podem participar do projeto pessoas acima de 60 anos que estejam inseridas em algum grupo organizado, como ONGs, institui\u00e7\u00f5es assistenciais, faculdades e no pr\u00f3prio CRISA.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resgate hist\u00f3rico visa mostrar a transforma\u00e7\u00e3o da paisagem urbana Inserir a popula\u00e7\u00e3o da terceira idade de Santo Andr\u00e9 aos conceitos de preserva\u00e7\u00e3o do meio ambiente urbano e promover o resgate hist\u00f3rico do meio em que vivem \u00e9 o objetivo do curso de educa\u00e7\u00e3o ambiental para idosos promovido pelo Semasa (Servi\u00e7o Municipal de Saneamento Ambiental de [&hellip;]<\/p>\n","protected":false},"author":60,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,8],"tags":[],"class_list":["post-2566","post","type-post","status-publish","format-standard","hentry","category-educacao-ambiental","category-releases"],"_links":{"self":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/2566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/comments?post=2566"}],"version-history":[{"count":1,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/2566\/revisions"}],"predecessor-version":[{"id":2567,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/2566\/revisions\/2567"}],"wp:attachment":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/media?parent=2566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/categories?post=2566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/tags?post=2566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}