{"id":2251,"date":"2024-11-13T19:32:00","date_gmt":"2024-11-13T22:32:00","guid":{"rendered":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/?p=2251"},"modified":"2024-11-14T06:32:40","modified_gmt":"2024-11-14T09:32:40","slug":"semasa-completa-55-anos-com-foco-na-atuacao-contra-a-crise-climatica","status":"publish","type":"post","link":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/2024\/11\/13\/semasa-completa-55-anos-com-foco-na-atuacao-contra-a-crise-climatica\/","title":{"rendered":"Semasa completa 55 anos com foco na atua\u00e7\u00e3o contra a crise clim\u00e1tica"},"content":{"rendered":"\n<p><em>Autarquia de Santo Andr\u00e9 refor\u00e7ou servi\u00e7os de combate a crimes ambientais e projetos de educa\u00e7\u00e3o ambiental<\/em><\/p>\n\n\n\n<p>Santo Andr\u00e9, 13 de novembro de 2024 \u2013 H\u00e1 exatos 55 anos, em 13 de novembro de 1969, o munic\u00edpio de Santo Andr\u00e9 registrava um importante avan\u00e7o para fortalecer e instrumentalizar o servi\u00e7o de saneamento. No lugar do DAE (Departamento de \u00c1gua e Esgoto), \u00f3rg\u00e3o da administra\u00e7\u00e3o direta, nascia o Semasa, denominado desde 1998 como Servi\u00e7o Municipal de Saneamento Ambiental de Santo Andr\u00e9.<\/p>\n\n\n\n<p>Ao longo dessas d\u00e9cadas, a autarquia passou por algumas reestrutura\u00e7\u00f5es, ganhando novos servi\u00e7os, a exemplo da gest\u00e3o de res\u00edduos s\u00f3lidos e ambiental, e, posteriormente, deixando de gerenciar atribui\u00e7\u00f5es relacionadas \u00e0 gest\u00e3o de \u00e1gua, esgoto, drenagem e riscos ambientais, promovida pela Defesa Civil.<\/p>\n\n\n\n<p>Nesta d\u00e9cada atual, o Semasa, que \u00e9 detentor da Pol\u00edtica Municipal de Gest\u00e3o e Saneamento Ambiental de Santo Andr\u00e9 (Lei 7.733\/1998) e respons\u00e1vel por manter o meio ambiente equilibrado, busca oferecer diretrizes ao poder p\u00fablico e \u00e0 coletividade para a defesa, conserva\u00e7\u00e3o e recupera\u00e7\u00e3o da qualidade e salubridade ambiental, com vistas ao desenvolvimento sustent\u00e1vel e, assim, a autarquia torna-se protagonista para enfrentar o maior desafio deste s\u00e9culo: as mudan\u00e7as clim\u00e1ticas.<\/p>\n\n\n\n<p>\u201c\u00c9 a nossa pol\u00edtica que prop\u00f5e, orienta, executa e coordena, direta ou indiretamente, a pol\u00edtica ambiental de Santo Andr\u00e9. Por isso, deixamos um legado muito importante para a cidade de como tratar e atuar frente \u00e0s quest\u00f5es relacionadas ao meio ambiente\u201d, explica o superintendente do Semasa, Ajan Marques de Oliveira.<\/p>\n\n\n\n<p>Todos os servi\u00e7os executados pela autarquia s\u00e3o fundamentais para o bem-estar individual, coletivo e ambiental. No Departamento de Gest\u00e3o Ambiental, o Semasa realiza eventos, cursos, palestras, programas e projetos de educa\u00e7\u00e3o ambiental, sensibilizando a popula\u00e7\u00e3o e transformando a sua rela\u00e7\u00e3o com o meio ambiental.<\/p>\n\n\n\n<p>Al\u00e9m disso, o setor \u00e9 respons\u00e1vel por fiscalizar e combater a polui\u00e7\u00e3o do ar, do solo e da \u00e1gua e outros tipos de crimes ambientais, como descarte ilegal de res\u00edduos, movimenta\u00e7\u00e3o irregular de terra, supress\u00e3o de vegeta\u00e7\u00e3o, polui\u00e7\u00e3o sonora, queima a c\u00e9u aberto, pesca com tarrafa em \u00e1rea de manancial, esgoto a c\u00e9u aberto e vazamento de produtos qu\u00edmicos.<\/p>\n\n\n\n<p>O Semasa tamb\u00e9m realiza o licenciamento ambiental, procedimento que a autarquia aprova a constru\u00e7\u00e3o, instala\u00e7\u00e3o e opera\u00e7\u00e3o de empreendimentos potencialmente impactantes ao meio ambiente, al\u00e9m de outras atividades como an\u00e1lises ambientais para implanta\u00e7\u00e3o de obras vi\u00e1rias , movimenta\u00e7\u00e3o de terra, supress\u00e3o de vegeta\u00e7\u00e3o e interven\u00e7\u00e3o em \u00e1rea de prote\u00e7\u00e3o permanente. O \u00f3rg\u00e3o avalia os impactos dessas a\u00e7\u00f5es, determinando medidas de controle, mitiga\u00e7\u00e3o e compensa\u00e7\u00e3o ambiental.<\/p>\n\n\n\n<p><strong>Gest\u00e3o de res\u00edduos \u2013<\/strong> Outra importante atua\u00e7\u00e3o do Semasa \u00e9 na gest\u00e3o de res\u00edduos s\u00f3lidos, \u00e1rea em que h\u00e1 a realiza\u00e7\u00e3o dos servi\u00e7os de coleta porta a porta, limpeza de vias, reposi\u00e7\u00e3o e manuten\u00e7\u00e3o de lixeiras, gerenciamento do Aterro Sanit\u00e1rio Municipal, opera\u00e7\u00e3o das Esta\u00e7\u00f5es de Coleta (ecopontos) e desenvolvimento e coordena\u00e7\u00e3o de pol\u00edticas p\u00fablicas relacionadas \u00e0 reciclagem, compostagem e reaproveitamento de materiais.&nbsp;<\/p>\n\n\n\n<p>\u201cA educa\u00e7\u00e3o ambiental, o descarte correto de res\u00edduos e a amplia\u00e7\u00e3o da reciclagem s\u00e3o fatores que contribuem para minimizar a emiss\u00e3o de gases de efeito estufa na atmosfera, como metano e di\u00f3xido de carbono, ajudando a combater as mudan\u00e7as clim\u00e1ticas\u201d, explica o superintendente adjunto do Semasa, Edinilson Ferreira dos Santos. Para sensibilizar os mun\u00edcipes sobre a import\u00e2ncia da ades\u00e3o a h\u00e1bitos sustent\u00e1veis e dos impactos que a crise clim\u00e1tica traz tanto para o meio ambiente quanto para a sa\u00fade, a autarquia vem fortalecendo as a\u00e7\u00f5es educativas e de fiscaliza\u00e7\u00e3o, al\u00e9m de projetos e programas socioambientais e atividades com outros atores importantes, como os catadores aut\u00f4nomos de materiais recicl\u00e1veis e os agricultores urbanos, que podem contribuir para a redu\u00e7\u00e3o da emiss\u00e3o de carbono por meio do plantio, do manejo do solo e da compostagem.<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Autarquia de Santo Andr\u00e9 refor\u00e7ou servi\u00e7os de combate a crimes ambientais e projetos de educa\u00e7\u00e3o ambiental Santo Andr\u00e9, 13 de novembro de 2024 \u2013 H\u00e1 exatos 55 anos, em 13 de novembro de 1969, o munic\u00edpio de Santo Andr\u00e9 registrava um importante avan\u00e7o para fortalecer e instrumentalizar o servi\u00e7o de saneamento. No lugar do DAE [&hellip;]<\/p>\n","protected":false},"author":28,"featured_media":2252,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,8],"tags":[],"class_list":["post-2251","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-institucional","category-releases"],"_links":{"self":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/2251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/comments?post=2251"}],"version-history":[{"count":1,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/2251\/revisions"}],"predecessor-version":[{"id":2253,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/posts\/2251\/revisions\/2253"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/media\/2252"}],"wp:attachment":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/media?parent=2251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/categories?post=2251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/semasa\/wp-json\/wp\/v2\/tags?post=2251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}