{"id":977,"date":"2025-02-05T15:56:36","date_gmt":"2025-02-05T18:56:36","guid":{"rendered":"https:\/\/portais.santoandre.sp.gov.br\/gcm\/?p=977"},"modified":"2025-05-08T16:05:01","modified_gmt":"2025-05-08T19:05:01","slug":"gcm-em-acao-9","status":"publish","type":"post","link":"https:\/\/portais.santoandre.sp.gov.br\/gcm\/2025\/02\/05\/gcm-em-acao-9\/","title":{"rendered":"GCM EM A\u00c7\u00c3O"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/portais.santoandre.sp.gov.br\/gcm\/wp-content\/uploads\/sites\/7\/2025\/02\/WhatsApp-Image-2025-01-29-at-08.52.02-819x1024.jpeg\" alt=\"\" class=\"wp-image-978\" srcset=\"https:\/\/portais.santoandre.sp.gov.br\/gcm\/wp-content\/uploads\/sites\/7\/2025\/02\/WhatsApp-Image-2025-01-29-at-08.52.02-819x1024.jpeg 819w, https:\/\/portais.santoandre.sp.gov.br\/gcm\/wp-content\/uploads\/sites\/7\/2025\/02\/WhatsApp-Image-2025-01-29-at-08.52.02-240x300.jpeg 240w, https:\/\/portais.santoandre.sp.gov.br\/gcm\/wp-content\/uploads\/sites\/7\/2025\/02\/WhatsApp-Image-2025-01-29-at-08.52.02-768x960.jpeg 768w, https:\/\/portais.santoandre.sp.gov.br\/gcm\/wp-content\/uploads\/sites\/7\/2025\/02\/WhatsApp-Image-2025-01-29-at-08.52.02.jpeg 1080w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/><\/figure>\n\n\n\n<p>Santo Andr\u00e9, 29 de janeiro de 2025.<br>Secret\u00e1ria de Seguran\u00e7a Cidad\u00e3.<\/p>\n\n\n\n<p>Natureza: Auto localizado<br>Data: 28\/01\/2025<\/p>\n\n\n\n<p>Local: Rua Ant\u00f4nio Francisco Lisboa, Jardim Teles de Menezes, Santo Andr\u00e9 &#8211; SP<\/p>\n\n\n\n<p>Equipe:<\/p>\n\n\n\n<p>3-11<br>Apoio: 3-12<\/p>\n\n\n\n<p>O Centro de Opera\u00e7\u00f5es Integradas (COI) informou via telefone ao Centro de Comunica\u00e7\u00f5es (CECOM) sobre o roubo de um ve\u00edculo T-Cross branco, com placa XXXXX, ocorrido momentos antes.<\/p>\n\n\n\n<p>O sistema de rastreamento do ve\u00edculo indicava sua localiza\u00e7\u00e3o na Rua Ant\u00f4nio Francisco Lisboa e imedia\u00e7\u00f5es.<br>A viatura 3-11, acionada via CECOM, realizou patrulhamento preventivo na regi\u00e3o e localizou o ve\u00edculo abandonado na referida via p\u00fablica.<br>O CECOM entrou em contato com o propriet\u00e1rio, que compareceu ao local.<br>A autoridade policial de plant\u00e3o do 6\u00b0 DP foi contatada, e a GCM a elaborou o Boletim de Ocorr\u00eancia (BOGCM).<br>A equipe conduziu a v\u00edtima e o ve\u00edculo at\u00e9 a 5\u00b0 Cia da PM para realizar a baixa no sistema.<\/p>\n\n\n\n<p>O ve\u00edculo foi recuperado e restitu\u00eddo ao propriet\u00e1rio.<\/p>\n\n\n\n<p>Rela\u00e7\u00f5es P\u00fablicas \/SSC<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Andr\u00e9, 29 de janeiro de 2025.Secret\u00e1ria de Seguran\u00e7a Cidad\u00e3. Natureza: Auto localizadoData: 28\/01\/2025 Local: Rua Ant\u00f4nio Francisco Lisboa, Jardim Teles de Menezes, Santo Andr\u00e9 &#8211; SP Equipe: 3-11Apoio: 3-12 O Centro de Opera\u00e7\u00f5es Integradas (COI) informou via telefone ao Centro de Comunica\u00e7\u00f5es (CECOM) sobre o roubo de um ve\u00edculo T-Cross branco, com placa XXXXX, [&hellip;]<\/p>\n","protected":false},"author":48,"featured_media":978,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-977","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/gcm\/wp-json\/wp\/v2\/posts\/977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/gcm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/gcm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/gcm\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/gcm\/wp-json\/wp\/v2\/comments?post=977"}],"version-history":[{"count":1,"href":"https:\/\/portais.santoandre.sp.gov.br\/gcm\/wp-json\/wp\/v2\/posts\/977\/revisions"}],"predecessor-version":[{"id":979,"href":"https:\/\/portais.santoandre.sp.gov.br\/gcm\/wp-json\/wp\/v2\/posts\/977\/revisions\/979"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/gcm\/wp-json\/wp\/v2\/media\/978"}],"wp:attachment":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/gcm\/wp-json\/wp\/v2\/media?parent=977"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/gcm\/wp-json\/wp\/v2\/categories?post=977"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/gcm\/wp-json\/wp\/v2\/tags?post=977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}