{"id":961,"date":"2025-02-05T15:44:22","date_gmt":"2025-02-05T18:44:22","guid":{"rendered":"https:\/\/portais.santoandre.sp.gov.br\/gcm\/?p=961"},"modified":"2025-02-05T15:44:22","modified_gmt":"2025-02-05T18:44:22","slug":"gcm-em-acao-4","status":"publish","type":"post","link":"https:\/\/portais.santoandre.sp.gov.br\/gcm\/2025\/02\/05\/gcm-em-acao-4\/","title":{"rendered":"GCM EM A\u00c7\u00c3O"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/portais.santoandre.sp.gov.br\/gcm\/wp-content\/uploads\/sites\/7\/2025\/02\/20-819x1024.png\" alt=\"\" class=\"wp-image-954\" srcset=\"https:\/\/portais.santoandre.sp.gov.br\/gcm\/wp-content\/uploads\/sites\/7\/2025\/02\/20-819x1024.png 819w, https:\/\/portais.santoandre.sp.gov.br\/gcm\/wp-content\/uploads\/sites\/7\/2025\/02\/20-240x300.png 240w, https:\/\/portais.santoandre.sp.gov.br\/gcm\/wp-content\/uploads\/sites\/7\/2025\/02\/20-768x960.png 768w, https:\/\/portais.santoandre.sp.gov.br\/gcm\/wp-content\/uploads\/sites\/7\/2025\/02\/20.png 1080w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/><\/figure>\n\n\n\n<p>Santo Andr\u00e9, 18 de janeiro de 2025.<br>Secretaria de Seguran\u00e7a Cidad\u00e3.<\/p>\n\n\n\n<p>Santo Andr\u00e9 intensifica combate ao crime e recupera 189 ve\u00edculos em 2024.<\/p>\n\n\n\n<p>A Prefeitura de Santo Andr\u00e9, em sua constante busca por um munic\u00edpio ainda mais seguro, alcan\u00e7ou um marco significativo no combate ao crime em 2024.<\/p>\n\n\n\n<p>Os dados oficiais apontam para a recupera\u00e7\u00e3o de 189 ve\u00edculos ao passar pela MURALHA ELETR\u00d4NICO um resultado expressivo que demonstra a efic\u00e1cia das a\u00e7\u00f5es implementadas pela administra\u00e7\u00e3o municipal.<\/p>\n\n\n\n<p>Al\u00e9m da tecnologia, a Prefeitura de Santo Andr\u00e9 tem intensificado a parceria com as for\u00e7as de seguran\u00e7a, promovendo a troca de informa\u00e7\u00f5es e a realiza\u00e7\u00e3o de opera\u00e7\u00f5es conjuntas.<\/p>\n\n\n\n<p>Atrav\u00e9s de investimentos cont\u00ednuos em tecnologia e intelig\u00eancia artificial, a Prefeitura de Santo Andr\u00e9 ir\u00e1 aprimorar ainda mais seus sistemas de monitoramento. A amplia\u00e7\u00e3o da rede de c\u00e2meras de seguran\u00e7a, a integra\u00e7\u00e3o de dados e o uso de ferramentas anal\u00edticas avan\u00e7adas.<\/p>\n\n\n\n<p>Os resultados obtidos em 2024 demonstram o compromisso da Prefeitura de Santo Andr\u00e9 por meio da Secretaria de Seguran\u00e7a Cidad\u00e3 em garantir a seguran\u00e7a dos cidad\u00e3os e fortalecer a sensa\u00e7\u00e3o de bem-estar na cidade.<\/p>\n\n\n\n<p>Rela\u00e7\u00f5es P\u00fablicas\/SSC\/COi<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Andr\u00e9, 18 de janeiro de 2025.Secretaria de Seguran\u00e7a Cidad\u00e3. Santo Andr\u00e9 intensifica combate ao crime e recupera 189 ve\u00edculos em 2024. A Prefeitura de Santo Andr\u00e9, em sua constante busca por um munic\u00edpio ainda mais seguro, alcan\u00e7ou um marco significativo no combate ao crime em 2024. Os dados oficiais apontam para a recupera\u00e7\u00e3o de [&hellip;]<\/p>\n","protected":false},"author":48,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-961","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/gcm\/wp-json\/wp\/v2\/posts\/961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/gcm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/gcm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/gcm\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/gcm\/wp-json\/wp\/v2\/comments?post=961"}],"version-history":[{"count":1,"href":"https:\/\/portais.santoandre.sp.gov.br\/gcm\/wp-json\/wp\/v2\/posts\/961\/revisions"}],"predecessor-version":[{"id":962,"href":"https:\/\/portais.santoandre.sp.gov.br\/gcm\/wp-json\/wp\/v2\/posts\/961\/revisions\/962"}],"wp:attachment":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/gcm\/wp-json\/wp\/v2\/media?parent=961"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/gcm\/wp-json\/wp\/v2\/categories?post=961"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/gcm\/wp-json\/wp\/v2\/tags?post=961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}