{"id":506,"date":"2024-06-04T12:09:10","date_gmt":"2024-06-04T15:09:10","guid":{"rendered":"https:\/\/portais.santoandre.sp.gov.br\/gcm\/?p=506"},"modified":"2024-06-04T12:09:10","modified_gmt":"2024-06-04T15:09:10","slug":"evento-de-lancamento-do-programa-de-capacitacao-patrulha-maria-da-penha","status":"publish","type":"post","link":"https:\/\/portais.santoandre.sp.gov.br\/gcm\/2024\/06\/04\/evento-de-lancamento-do-programa-de-capacitacao-patrulha-maria-da-penha\/","title":{"rendered":"Evento de lan\u00e7amento do programa de capacita\u00e7\u00e3o Patrulha Maria da Penha"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/portais.santoandre.sp.gov.br\/gcm\/wp-content\/uploads\/sites\/7\/2024\/06\/IMG-20240529-WA0045-1024x576.jpg\" alt=\"\" class=\"wp-image-508\" style=\"aspect-ratio:1.7777777777777777;width:506px;height:auto\" srcset=\"https:\/\/portais.santoandre.sp.gov.br\/gcm\/wp-content\/uploads\/sites\/7\/2024\/06\/IMG-20240529-WA0045-1024x576.jpg 1024w, https:\/\/portais.santoandre.sp.gov.br\/gcm\/wp-content\/uploads\/sites\/7\/2024\/06\/IMG-20240529-WA0045-300x169.jpg 300w, https:\/\/portais.santoandre.sp.gov.br\/gcm\/wp-content\/uploads\/sites\/7\/2024\/06\/IMG-20240529-WA0045-768x432.jpg 768w, https:\/\/portais.santoandre.sp.gov.br\/gcm\/wp-content\/uploads\/sites\/7\/2024\/06\/IMG-20240529-WA0045.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>No dia 29\/05\/2024 houve o evento de lan\u00e7amento do programa de capacita\u00e7\u00e3o Patrulha Maria da Penha em parceria com a Escola de Governo que busca capacitar o p\u00fablico interno bem como as guardas de outros munic\u00edpios, departamentos e governos que j\u00e1 possuem ou queiram implantar unidades de patrulha para a defesa da mulher.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No dia 29\/05\/2024 houve o evento de lan\u00e7amento do programa de capacita\u00e7\u00e3o Patrulha Maria da Penha em parceria com a Escola de Governo que busca capacitar o p\u00fablico interno bem como as guardas de outros munic\u00edpios, departamentos e governos que j\u00e1 possuem ou queiram implantar unidades de patrulha para a defesa da mulher.<\/p>\n","protected":false},"author":48,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-506","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/gcm\/wp-json\/wp\/v2\/posts\/506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/gcm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/gcm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/gcm\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/gcm\/wp-json\/wp\/v2\/comments?post=506"}],"version-history":[{"count":1,"href":"https:\/\/portais.santoandre.sp.gov.br\/gcm\/wp-json\/wp\/v2\/posts\/506\/revisions"}],"predecessor-version":[{"id":510,"href":"https:\/\/portais.santoandre.sp.gov.br\/gcm\/wp-json\/wp\/v2\/posts\/506\/revisions\/510"}],"wp:attachment":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/gcm\/wp-json\/wp\/v2\/media?parent=506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/gcm\/wp-json\/wp\/v2\/categories?post=506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/gcm\/wp-json\/wp\/v2\/tags?post=506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}