{"id":942,"date":"2020-06-12T13:29:15","date_gmt":"2020-06-12T16:29:15","guid":{"rendered":"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/?p=942"},"modified":"2025-09-03T12:10:30","modified_gmt":"2025-09-03T15:10:30","slug":"solidariedade-ariel-expande-opoderdecompartilhar-para-o-chm-de-santo-andre","status":"publish","type":"post","link":"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/2020\/06\/12\/solidariedade-ariel-expande-opoderdecompartilhar-para-o-chm-de-santo-andre\/","title":{"rendered":"Solidariedade: Ariel expande #OPoderdeCompartilhar para o CHM de Santo Andr\u00e9"},"content":{"rendered":"\n<div class=\"wp-block-stackable-image stk-block-image stk-block stk-d48e98c\" data-block-id=\"d48e98c\"><style>.stk-d48e98c .stk-img-wrapper{width:640px !important;}<\/style><figure><span class=\"stk-img-wrapper stk-image--shape-stretch\"><img fetchpriority=\"high\" decoding=\"async\" class=\"stk-img wp-image-943\" src=\"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-content\/uploads\/sites\/29\/2025\/04\/ariel-chm-1.jpg\" width=\"640\" height=\"360\" srcset=\"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-content\/uploads\/sites\/29\/2025\/04\/ariel-chm-1.jpg 640w, https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-content\/uploads\/sites\/29\/2025\/04\/ariel-chm-1-300x169.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/span><\/figure><\/div>\n\n\n\n<p>A Ariel, marca de lavar roupas da P&amp;G (Procter &amp; Gamble), decidiu expandir o posicionamento #OPoderdeCompartihar para al\u00e9m da doa\u00e7\u00e3o de produtos de higiene e limpeza \u00e0s comunidades carentes. Por meio do servi\u00e7o das lavanderias Ariel, ser\u00e3o lavadas 46 mil pe\u00e7as de roupas de profissionais da sa\u00fade que trabalham em hospitais e entre os locais escolhidos est\u00e1 o Centro Hospitalar Municipal de Santo Andr\u00e9 Dr. Newton da Costa Brand\u00e3o.<\/p>\n\n\n\n<p>\u201cA pandemia da Covid-19 afetou a rotina das pessoas que trabalham em hospitais. N\u00e3o bastasse o cansa\u00e7o, todos est\u00e3o sem tempo e esse suporte para a lavagem das roupas \u00e9 uma maneira de retribuir a dedica\u00e7\u00e3o desses profissionais\u201d, diz&nbsp;<strong>Tarcio Pinto<\/strong>, empres\u00e1rio da Lavanderia Ariel encarregada da coleta de roupas no CHMSA. A lavanderia chegava a atender 5.000 quartos da rede hoteleira, mas devido \u00e0s restri\u00e7\u00f5es sanit\u00e1rias impostas ao setor essa for\u00e7a foi concentrada em apoio aos hospitais.<\/p>\n\n\n\n<p>Em todos os pa\u00edses onde est\u00e1 presente, a P&amp;G vem divulgando a m\u00e1xima de que \u201cCompartilhar Nos Faz Melhores\u201d como forma de incentivar os consumidores ao melhor aproveitamento dos produtos e \u00e0 divis\u00e3o das tarefas di\u00e1rias da casa, al\u00e9m da ajuda ao pr\u00f3ximo. S\u00e3o tr\u00eas os pilares da iniciativa: Compartilhar Recursos, Compartilhar Tarefas Dom\u00e9sticas e Compartilhar Solidariedade para que possamos sair mais fortes desse momento de crise.<\/p>\n\n\n\n<p>Para a lavagem e higieniza\u00e7\u00e3o, as roupas s\u00e3o coletadas e devolvidas tr\u00eas vezes por semana. A repercuss\u00e3o tem sido positiva entre os profissionais do hospital. \u201cAmei o resultado. \u00c9 um gesto que demonstra a preocupa\u00e7\u00e3o da empresa com o nosso bem estar. Atitudes dessa natureza nos fazem sentir abra\u00e7adas e acolhidas\u201d, declara a m\u00e9dica intensivista&nbsp;<strong>Dra. Ana Helena Andrade<\/strong>, da UTI Adulto do CHMSA.<\/p>\n\n\n\n<p>Al\u00e9m do Centro Hospitalar Municipal de Santo Andr\u00e9, o Hospital Municipal de Mogi das Cruzes est\u00e1 contemplado pelo projeto. A Ariel ainda vai lavar 37 toneladas de pe\u00e7as do&nbsp;Ex\u00e9rcito da Salva\u00e7\u00e3o, institui\u00e7\u00e3o que realiza a\u00e7\u00f5es emergenciais para ajudar fam\u00edlias em vulnerabilidade social e moradores de rua \u2013 5 mil m\u00e1scaras de prote\u00e7\u00e3o tamb\u00e9m ser\u00e3o doadas para a ONG.<\/p>\n\n\n\n<p>J\u00e1 para a&nbsp;Cruz Vermelha Brasileira o apoio da marca veio com a doa\u00e7\u00e3o de mais de 30 toneladas de produtos para contribuir com a higieniza\u00e7\u00e3o da principal institui\u00e7\u00e3o de ajuda humanit\u00e1ria do mundo. Para as comunidades carentes, foram destinadas mais de 30 toneladas de produtos e compartilhadas dicas informativas sobre como prevenir da contamina\u00e7\u00e3o pelo coronav\u00edrus.<\/p>\n\n\n\n<p><strong>Preven\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p>De \u00e1lcool gel a equipamentos de prote\u00e7\u00e3o, as doa\u00e7\u00f5es de empresas e volunt\u00e1rios ao Centro Hospitalar Municipal de Santo Andr\u00e9 seguem a todo vapor nesse per\u00edodo, como forma de reconhecimento e apoio ao trabalho dos profissionais da sa\u00fade que est\u00e3o na linha de frente. No \u00faltimo dia 04, foram entregues 5 mil m\u00e1scaras de TNT para prote\u00e7\u00e3o pela disciplina de Ortopedia da FMABC (Faculdade de Medicina do ABC) por meio da campanha ABCDoe.<\/p>\n\n\n\n<p>Os itens foram recebidos por&nbsp;<strong>Braulio Cesar Augusto<\/strong>&nbsp;e&nbsp;<strong>Rosa Maria Cussolini Betarelli<\/strong>, gerentes administrativos do CHMSA. A campanha ABCDoe, representada na ocasi\u00e3o pelo&nbsp;<strong>Dr. Roberto Picarte Milani<\/strong>, \u00e9 resultado da uni\u00e3o de m\u00e9dicos, residentes e alunos de Medicina da FMABC com o objetivo de arrecadar fundos para combater a pandemia do novo coronav\u00edrus.<\/p>\n\n\n\n<p><em><strong>Fonte: Comunica\u00e7\u00e3o CHMSA \u201cDr. Newton da Costa Brand\u00e3o\u201d<\/strong><\/em><br><em>Supervis\u00e3o: Gustavo Baena<\/em><br><em>Fotos: Comunica\u00e7\u00e3o CHMSA<\/em><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"640\" height=\"480\" data-id=\"945\" src=\"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-content\/uploads\/sites\/29\/2025\/04\/ariel-chm-2.jpg\" alt=\"\" class=\"wp-image-945\" srcset=\"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-content\/uploads\/sites\/29\/2025\/04\/ariel-chm-2.jpg 640w, https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-content\/uploads\/sites\/29\/2025\/04\/ariel-chm-2-300x225.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"640\" height=\"360\" data-id=\"944\" src=\"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-content\/uploads\/sites\/29\/2025\/04\/abcdoe-mascaras.jpg\" alt=\"\" class=\"wp-image-944\" srcset=\"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-content\/uploads\/sites\/29\/2025\/04\/abcdoe-mascaras.jpg 640w, https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-content\/uploads\/sites\/29\/2025\/04\/abcdoe-mascaras-300x169.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>A Ariel, marca de lavar roupas da P&amp;G (Procter &amp; Gamble), decidiu expandir o posicionamento #OPoderdeCompartihar para al\u00e9m da doa\u00e7\u00e3o de produtos de higiene e limpeza \u00e0s comunidades carentes. Por meio do servi\u00e7o das lavanderias Ariel, ser\u00e3o lavadas 46 mil pe\u00e7as de roupas de profissionais da sa\u00fade que trabalham em hospitais e entre os locais [&hellip;]<\/p>\n","protected":false},"author":77,"featured_media":943,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-942","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-json\/wp\/v2\/posts\/942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-json\/wp\/v2\/users\/77"}],"replies":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-json\/wp\/v2\/comments?post=942"}],"version-history":[{"count":1,"href":"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-json\/wp\/v2\/posts\/942\/revisions"}],"predecessor-version":[{"id":946,"href":"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-json\/wp\/v2\/posts\/942\/revisions\/946"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-json\/wp\/v2\/media\/943"}],"wp:attachment":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-json\/wp\/v2\/media?parent=942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-json\/wp\/v2\/categories?post=942"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-json\/wp\/v2\/tags?post=942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}