{"id":463,"date":"2019-04-23T10:24:17","date_gmt":"2019-04-23T13:24:17","guid":{"rendered":"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/?p=463"},"modified":"2025-09-03T11:49:46","modified_gmt":"2025-09-03T14:49:46","slug":"forca-tarefa-do-saude-fila-zero-beneficia-25-mil-pessoas-com-consultas-de-endocrinologia-e-otorrinolaringologia","status":"publish","type":"post","link":"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/2019\/04\/23\/forca-tarefa-do-saude-fila-zero-beneficia-25-mil-pessoas-com-consultas-de-endocrinologia-e-otorrinolaringologia\/","title":{"rendered":"For\u00e7a-tarefa do Sa\u00fade Fila Zero beneficia 2,5 mil pessoas com consultas de endocrinologia e otorrinolaringologia"},"content":{"rendered":"\n<div class=\"wp-block-stackable-image stk-block-image stk-block stk-39f08e1\" data-block-id=\"39f08e1\"><style>.stk-39f08e1 .stk-img-wrapper{width:700px !important;}<\/style><figure><span class=\"stk-img-wrapper stk-image--shape-stretch\"><img fetchpriority=\"high\" decoding=\"async\" class=\"stk-img wp-image-464\" src=\"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-content\/uploads\/sites\/29\/2025\/04\/endocrino_e_otorrino.jpg\" width=\"700\" height=\"465\" srcset=\"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-content\/uploads\/sites\/29\/2025\/04\/endocrino_e_otorrino.jpg 700w, https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-content\/uploads\/sites\/29\/2025\/04\/endocrino_e_otorrino-300x199.jpg 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/span><\/figure><\/div>\n\n\n\n<p>A Prefeitura de Santo Andr\u00e9 est\u00e1 realizando mais uma for\u00e7a-tarefa noturna do programa Sa\u00fade Fila Zero, desta vez com o objetivo de zerar a fila de&nbsp;espera por consultas na \u00e1rea de endocrinologia infantil e otorrinolaringologia adulto e infantil. Os atendimentos, que foram previamente agendados, ocorrem no Centro Hospitalar&nbsp;Municipal Dr. Newton da Costa Brand\u00e3o (CHMSA), das 17h \u00e0s 22h.<\/p>\n\n\n\n<p>&nbsp;As consultas foram marcadas respeitando a ordem cronol\u00f3gica da fila de espera. Os atendimentos tiveram in\u00edcio no dia 15 de abril e terminar\u00e3o nesta quinta-feira (25), beneficiando cerca de 2,5 mil pessoas.<\/p>\n\n\n\n<p>\u201cEstamos realizando um grande esfor\u00e7o na Sa\u00fade para eliminar a fila de espera por consultas e exames nas especialidades. A for\u00e7a-tarefa em endocrinologia e otorrinolaringologia \u00e9 mais uma a\u00e7\u00e3o priorit\u00e1ria para garantir atendimento \u00e1gil, eficiente e de qualidade \u00e0 popula\u00e7\u00e3o\u201d, comentou o prefeito&nbsp;<strong>Paulo Serra<\/strong>.<\/p>\n\n\n\n<p>Para n\u00e3o gerar uma nova fila de espera e garantir que os pacientes realizem todo o processo at\u00e9 a alta m\u00e9dica, a for\u00e7a-tarefa foi dividida em etapas. Ap\u00f3s o primeiro atendimento, se necess\u00e1rio, os pacientes ser\u00e3o encaminhados para realizar exames de diagn\u00f3stico e retorno m\u00e9dico. Os casos que necessitem de acompanhamento posterior ser\u00e3o direcionados \u00e0 rede de aten\u00e7\u00e3o especializada.<\/p>\n\n\n\n<p>No atendimento com endocrinologia infantil, inicialmente os pacientes passam por uma triagem onde s\u00e3o realizadas aferi\u00e7\u00e3o de press\u00e3o, peso, altura e dextro (exame que mede a glicose presente no sangue).<\/p>\n\n\n\n<p>\u201cO profissional que atende a especialidade de endocrinologia \u00e9 procurado por in\u00fameros fatores. Hoje os que mais prevalecem s\u00e3o puberdade precoce, colesterol alto, obesidade, tire\u00f3ide e baixa estatura. Orientamos, na maioria das vezes, como primeiro tratamento, dieta e atividade f\u00edsica\u201d, explicou a endocrinologista&nbsp;<strong>Dra. Giovana de Castro Oliveira Franzon<\/strong>.<\/p>\n\n\n\n<p>A costureira&nbsp;<strong>Mirian Santos Cavalcante<\/strong>, de 34 anos, participou da iniciativa acompanhando as filhas,&nbsp;<strong>Sara<\/strong>&nbsp;e&nbsp;<strong>Soraia<\/strong>, de seis anos de idade, e ficou satisfeita com o atendimento que recebeu. \u201cDesde os tr\u00eas anos a Sara e a Soraia tinham muitos pelos, a m\u00e9dica do posto falou que poderia&nbsp;ser por quest\u00e3o hormonal e encaminhou para o endocrino. Foi pedido exame de raio-X para ver se a idade \u00f3ssea est\u00e1 avan\u00e7ada. Depois vou trazer o resultado para saber qual ser\u00e1 o tratamento. Eu gostei, achei legal, o atendimento aqui foi bem r\u00e1pido e organizado\u201d, elogiou a moradora da Vila Guiomar.<\/p>\n\n\n\n<p>J\u00e1 no atendimento com o otorrinolaringologista alguns procedimentos como lavagem de ouvido, cauteriza\u00e7\u00e3o e otoscopia s\u00e3o realizados dentro do consult\u00f3rio, durante a primeira consulta, em pacientes que apresentam essa necessidade.<\/p>\n\n\n\n<p>\u201cA reclama\u00e7\u00e3o mais recorrente que atendemos \u00e9 de rinite, principalmente nesse per\u00edodo de outono e inverno. Orientamos deixar a casa mais arejada, evitar o contato com lugares empoeirados, lavar as m\u00e3os com frequ\u00eancia, ingerir bastante l\u00edquido, e se poss\u00edvel, lavar o nariz com soro fisiol\u00f3gico tr\u00eas vezes por dia. Com isso \u00e9 poss\u00edvel evitar infec\u00e7\u00e3o por gripe e rinite virais, que s\u00e3o doen\u00e7as muito comuns nesta \u00e9poca do ano\u201d, orientou o otorrinolaringologia&nbsp;<strong>Dr. Everton Cardoso da Silva<\/strong>.<\/p>\n\n\n\n<p>Essa \u00e9 a terceira for\u00e7a-tarefa realizada em abril. Neste m\u00eas, foram realizados atendimentos tamb\u00e9m em gastroenterologia, pediatria, ginecologia e cl\u00ednico geral. Novas iniciativas ser\u00e3o realizadas at\u00e9 o final do m\u00eas para zerar a fila de outras especialidades.<\/p>\n\n\n\n<p><strong>Hist\u00f3rico \u2013<\/strong>&nbsp;O Programa Sa\u00fade Fila Zero foi lan\u00e7ado em 2017 com objetivo de zerar a fila de espera por consultas, exames e melhorar o fluxo de atendimento das demandas na \u00e1rea da Sa\u00fade. Em 2018, foram realizados mais de 400 mil procedimentos entre ultrassom, coleta de sangue, parasitol\u00f3gico e urina, consultas com dermatologista, neurologista adulto e pedi\u00e1trico, endocrinologista e oftalmologista.<\/p>\n\n\n\n<p><em><strong>Fonte:&nbsp;Comunica\u00e7\u00e3o PSA<\/strong><\/em><br><em>Foto: Angelo Baima \/ PSA<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Santo Andr\u00e9 est\u00e1 realizando mais uma for\u00e7a-tarefa noturna do programa Sa\u00fade Fila Zero, desta vez com o objetivo de zerar a fila de&nbsp;espera por consultas na \u00e1rea de endocrinologia infantil e otorrinolaringologia adulto e infantil. Os atendimentos, que foram previamente agendados, ocorrem no Centro Hospitalar&nbsp;Municipal Dr. Newton da Costa Brand\u00e3o (CHMSA), das [&hellip;]<\/p>\n","protected":false},"author":77,"featured_media":464,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-463","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-json\/wp\/v2\/posts\/463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-json\/wp\/v2\/users\/77"}],"replies":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-json\/wp\/v2\/comments?post=463"}],"version-history":[{"count":1,"href":"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-json\/wp\/v2\/posts\/463\/revisions"}],"predecessor-version":[{"id":465,"href":"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-json\/wp\/v2\/posts\/463\/revisions\/465"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-json\/wp\/v2\/media\/464"}],"wp:attachment":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-json\/wp\/v2\/media?parent=463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-json\/wp\/v2\/categories?post=463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-json\/wp\/v2\/tags?post=463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}