{"id":1143,"date":"2024-10-22T15:01:20","date_gmt":"2024-10-22T18:01:20","guid":{"rendered":"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/?p=1143"},"modified":"2025-09-03T12:20:19","modified_gmt":"2025-09-03T15:20:19","slug":"projeto-lean-nas-emergencias-realiza-diagnostico-no-chmsa","status":"publish","type":"post","link":"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/2024\/10\/22\/projeto-lean-nas-emergencias-realiza-diagnostico-no-chmsa\/","title":{"rendered":"Projeto Lean nas Emerg\u00eancias realiza diagn\u00f3stico no CHMSA"},"content":{"rendered":"\n<div class=\"wp-block-stackable-image stk-block-image stk-block stk-cfe8fd8\" data-block-id=\"cfe8fd8\"><style>.stk-cfe8fd8 .stk-img-wrapper{width:700px !important;}<\/style><figure><span class=\"stk-img-wrapper stk-image--shape-stretch\"><img fetchpriority=\"high\" decoding=\"async\" class=\"stk-img wp-image-1144\" src=\"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-content\/uploads\/sites\/29\/2025\/04\/lean-emergencias-chmsa.jpg\" width=\"700\" height=\"466\" srcset=\"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-content\/uploads\/sites\/29\/2025\/04\/lean-emergencias-chmsa.jpg 700w, https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-content\/uploads\/sites\/29\/2025\/04\/lean-emergencias-chmsa-300x200.jpg 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/span><\/figure><\/div>\n\n\n\n<p>O Centro Hospitalar Municipal de Santo Andr\u00e9 (CHMSA), unidade da Prefeitura gerenciada em parceria com a Funda\u00e7\u00e3o do ABC, acaba de passar por visita de diagn\u00f3stico dentro do Projeto Lean nas Emerg\u00eancias. O objetivo foi analisar os indicadores e fluxos da institui\u00e7\u00e3o, al\u00e9m de apresentar uma metodologia para controle desses dados, que auxiliar\u00e1 na tomada de decis\u00f5es estrat\u00e9gicas para otimizar a jornada dos pacientes dentro do hospital.<\/p>\n\n\n\n<p>O Projeto Lean nas Emerg\u00eancias \u00e9 uma iniciativa realizada no \u00e2mbito do Programa de Apoio ao Desenvolvimento Institucional do Sistema \u00danico de Sa\u00fade (PROADI-SUS), do Minist\u00e9rio da Sa\u00fade, e executada de forma colaborativa pelos hospitais BP \u2013 A Benefic\u00eancia Portuguesa e Hospital S\u00edrio-Liban\u00eas (HSL), em S\u00e3o Paulo, e Hospital Moinhos de Vento (HMV), em Porto Alegre. O objetivo \u00e9 reduzir a superlota\u00e7\u00e3o nas urg\u00eancias e emerg\u00eancias de hospitais p\u00fablicos e filantr\u00f3picos do Brasil.<\/p>\n\n\n\n<p>As indica\u00e7\u00f5es para participa\u00e7\u00e3o no projeto acontecem em ciclos, a cada seis meses, e s\u00e3o um consenso entre Minist\u00e9rio da Sa\u00fade, Conselho Nacional de Secret\u00e1rios de Sa\u00fade (CONASS) e Conselho Nacional de Secretarias Municipais de Sa\u00fade (CONASEMS). Para participar do projeto \u00e9 preciso obedecer a alguns crit\u00e9rios essenciais de elegibilidade, como estrutura, governan\u00e7a institucional e algumas caracter\u00edsticas da emerg\u00eancia.<\/p>\n\n\n\n<p><strong>Monitoramento cont\u00ednuo<\/strong><\/p>\n\n\n\n<p>Essa primeira visita diagn\u00f3stica ao CHMSA, realizada dias 02 e 03 de outubro, marca o in\u00edcio de um ciclo de um ano, com reuni\u00f5es presenciais e on-line para monitorar os indicadores e avaliar a redu\u00e7\u00e3o do tempo de atendimento dos pacientes. A metodologia Lean \u00e9 a base do projeto, complementada por outras ferramentas de gest\u00e3o, como o Kanban e o Kaizen.<\/p>\n\n\n\n<p>\u201c\u00c9 uma experi\u00eancia gratificante ver a equipe empenhada em buscar resultados e em potencializar a sa\u00fade p\u00fablica no Pa\u00eds\u201d, afirmou&nbsp;<strong>Dr. Willian Faria<\/strong>, diretor do CHMSA. O projeto, al\u00e9m de melhorar os fluxos, visa a redu\u00e7\u00e3o de custos e o aumento da efici\u00eancia nas atividades hospitalares.<\/p>\n\n\n\n<p>Ao otimizar o funcionamento do hospital, os impactos positivos se estendem para todo o sistema de sa\u00fade p\u00fablica, refor\u00e7ando o papel essencial do Sistema \u00danico de Sa\u00fade (SUS) e sua interconectividade na promo\u00e7\u00e3o da sa\u00fade.<\/p>\n\n\n\n<p><strong><em>Comunica\u00e7\u00e3o Centro Hospitalar Municipal de Santo Andr\u00e9 \u2013 CHMSA<\/em><\/strong><br><strong><em>Dr. Newton da Costa Brand\u00e3o<\/em><\/strong><br><em>Coordena\u00e7\u00e3o: Gustavo Baena<\/em><br><em>Foto: Rede de Aten\u00e7\u00e3o Hospitalar de Santo Andr\u00e9<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Centro Hospitalar Municipal de Santo Andr\u00e9 (CHMSA), unidade da Prefeitura gerenciada em parceria com a Funda\u00e7\u00e3o do ABC, acaba de passar por visita de diagn\u00f3stico dentro do Projeto Lean nas Emerg\u00eancias. O objetivo foi analisar os indicadores e fluxos da institui\u00e7\u00e3o, al\u00e9m de apresentar uma metodologia para controle desses dados, que auxiliar\u00e1 na tomada [&hellip;]<\/p>\n","protected":false},"author":77,"featured_media":1144,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1143","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-json\/wp\/v2\/posts\/1143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-json\/wp\/v2\/users\/77"}],"replies":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-json\/wp\/v2\/comments?post=1143"}],"version-history":[{"count":1,"href":"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-json\/wp\/v2\/posts\/1143\/revisions"}],"predecessor-version":[{"id":1145,"href":"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-json\/wp\/v2\/posts\/1143\/revisions\/1145"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-json\/wp\/v2\/media\/1144"}],"wp:attachment":[{"href":"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-json\/wp\/v2\/media?parent=1143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-json\/wp\/v2\/categories?post=1143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portais.santoandre.sp.gov.br\/chmsa\/wp-json\/wp\/v2\/tags?post=1143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}